{"id":11295,"date":"2025-01-27T21:34:43","date_gmt":"2025-01-27T21:34:43","guid":{"rendered":"https:\/\/www.eventurstp.com\/startseite\/"},"modified":"2025-09-04T11:48:37","modified_gmt":"2025-09-04T11:48:37","slug":"startseite","status":"publish","type":"page","link":"https:\/\/www.eventurstp.com\/de\/","title":{"rendered":"Startseite"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-1e5d1737 alignfull uagb-is-root-container\"><div class=\"uagb-container__video-wrap\"><video autoplay loop muted playsinline><source src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/09\/0904.mp4\" type=\"video\/mp4\"\/><\/video><\/div><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-cc9d733a uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Unvergessliche Erlebnisse in S\u00e3o Tom\u00e9 und Pr\u00edncipe<\/h1><\/div><p class=\"uagb-ifb-desc\">Entdecken Sie die Sch\u00f6nheit und Kultur von S\u00e3o Tom\u00e9 und Pr\u00edncipe mit unserer personalisierten Tourismus- und Eventagentur.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/www.eventurstp.com\/pacotes-turisticos-sao-tome-e-principe\/#reservas\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">Jetzt buchen<\/span><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-da6f24cd alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c8330bd6\"><p class=\"uagb-desc-text\">\u00dcber uns<\/p><h2 class=\"uagb-heading-text\">Wir schaffen f\u00fcr Sie einzigartige Erlebnisse in S\u00e3o Tom\u00e9 und Pr\u00edncipe.<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-29c74af9\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-23c95072\"><p class=\"uagb-heading-text\">Wir von EVENTUR haben es uns zur Aufgabe gemacht, unvergessliche Erinnerungen durch individuelle Reisen zu schaffen, die den kulturellen und nat\u00fcrlichen Reichtum der Inseln hervorheben.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-af8e0f11\"><p class=\"uagb-heading-text\">Unser engagiertes Team sorgt daf\u00fcr, dass jedes Detail sorgf\u00e4ltig geplant wird, um sicherzustellen, dass Ihr Erlebnis wirklich au\u00dfergew\u00f6hnlich und unvergesslich ist.<\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-75936b61\">\n<div class=\"wp-block-uagb-image uagb-block-3cc927cb wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/EVENTURSTP001-800X600.png ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/EVENTURSTP001-800X600.png 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/EVENTURSTP001-800X600.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/EVENTURSTP001-800X600.png\" alt=\"\" class=\"uag-image-10475\" width=\"182\" height=\"250\" title=\"\u00fcber-02\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-c2d11615 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/floresta_eventur.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/floresta_eventur.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/floresta_eventur.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/floresta_eventur.jpg\" alt=\"\" class=\"uag-image-10346\" width=\"234\" height=\"200\" title=\"\u00fcber-03\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-d8e6d73b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/JC0C6940.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/JC0C6940.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/JC0C6940.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/JC0C6940.jpg\" alt=\"\" class=\"uag-image-8556\" width=\"380\" height=\"300\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-179773c1 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/JC0C8999.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/JC0C8999.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/JC0C8999.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/JC0C8999.jpg\" alt=\"\" class=\"uag-image-10298\" width=\"330\" height=\"200\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-rglhekvi alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-lywptp7g\">\n<div class=\"wp-block-uagb-info-box uagb-block-ag6hx0t4 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title-prefix\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-0-color\">NUTZEN SIE DIESE GELEGENHEIT<\/mark><\/strong><\/p><h2 class=\"uagb-ifb-title\"><strong>\ud83c\udf34 Entdecken Sie S\u00e3o Tom\u00e9 und Pr\u00edncipe  <\/strong><\/h2><\/div><p class=\"uagb-ifb-desc\">\ud83d\udcbc <strong>Alles f\u00fcr Sie organisiert!<\/strong><br\/>\ud83d\udccb Was ist in dem Paket enthalten?<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-edea13a6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">  \u2705 Flug Lissabon S\u00e3o Tom\u00e9 &#8211; Lissabon<br\/> \u2705 Komfortable Unterkunft<br\/> \u2705 Alle Mahlzeiten.<br\/> \u2705 Transfers und Transport<br\/> \u2705 Unglaubliche Touren<br\/> \u2705 Spezialisierte Reiseleiter<br\/> \u2705 Authentische gastronomische Erfahrung<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-call-to-action uagb-block-71f28efb wp-block-button\"><div class=\"uagb-cta__wrap\"><h3 class=\"uagb-cta__title\">Buchen Sie jetzt Ihren Platz!<\/h3><\/div><div class=\"uagb-cta__buttons\"><a href=\"https:\/\/www.eventurstp.com\/pacotes-turisticos-sao-tome-e-principe\/#reservas\" class=\"uagb-cta__button-link-wrapper wp-block-button__link\" target=\"_blank\" rel=\"noopener noreferrer\">JETZT BUCHEN<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-e8fc30f4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-separator uagb-block-c890a0e3\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-4f6acc49\"><p class=\"uagb-desc-text\">Unsere Dienstleistungen<\/p><h2 class=\"uagb-heading-text\">Entdecken Sie unsere wichtigsten touristischen Dienstleistungen<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1e00a9da\">\n<div class=\"wp-block-uagb-image uagb-block-2acfa94e wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/familia-viajando-1024x683.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/familia-viajando-scaled.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/familia-viajando-scaled.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/familia-viajando-1024x683.jpg\" alt=\"\" class=\"uag-image-10669\" width=\"384\" height=\"290\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-8bca7b86 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Reiseplanung<\/h3><\/div><p class=\"uagb-ifb-desc\">Wir erstellen individuelle Reiserouten f\u00fcr eine einzigartige Reise.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c6ae55bb\">\n<div class=\"wp-block-uagb-image uagb-block-937370bc wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2022\/03\/JC0C1795.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2022\/03\/JC0C1795.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2022\/03\/JC0C1795.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2022\/03\/JC0C1795.jpg\" alt=\"\" class=\"uag-image-782\" width=\"384\" height=\"290\" title=\"JC0C1795.jpg\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-01946041 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Unterkunft Buchungen<\/h3><\/div><p class=\"uagb-ifb-desc\">Wir helfen Ihnen bei der Auswahl und Buchung der besten Unterkunft.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-32ab2baa\">\n<div class=\"wp-block-uagb-image uagb-block-8e3729f7 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/caogrande-1024x684.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/caogrande-e1678187159307.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/caogrande-e1678187159307.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/caogrande-1024x684.jpg\" alt=\"\" class=\"uag-image-8452\" width=\"384\" height=\"290\" title=\"caogrande\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-7e775245 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Gef\u00fchrte Aktivit\u00e4ten<\/h3><\/div><p class=\"uagb-ifb-desc\">Wir bieten spannende Touren und Aktivit\u00e4ten mit erfahrenen F\u00fchrern.<\/p><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-a79fbe43 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-6bf09454 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-call-to-action uagb-block-83ea0154 wp-block-button\"><div class=\"uagb-cta__wrap\"><h3 class=\"uagb-cta__title\">Planen Sie jetzt Ihr n\u00e4chstes Abenteuer!<\/h3><p class=\"uagb-cta__desc\">Entdecken Sie die Wunder von S\u00e3o Tom\u00e9 und Pr\u00edncipe auf Ihre eigene Art.<\/p><\/div><div class=\"uagb-cta__buttons\"><a href=\"https:\/\/www.eventurstp.com\/pacotes-turisticos-sao-tome-e-principe\/#reservas\" class=\"uagb-cta__button-link-wrapper wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\">Jetzt buchen<\/a><\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-4062d932 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-188bf86b\">\n<div class=\"wp-block-uagb-image alignright uagb-block-4ec4096e wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-right\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/eden-600x400-1.webp ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/eden-600x400-1.webp 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/eden-600x400-1.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/10\/eden-600x400-1.webp\" alt=\"\" class=\"uag-image-10302\" width=\"200\" height=\"150\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-58485396\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-afddea9c\"><h2 class=\"uagb-heading-text\">Warum sollten Sie uns w\u00e4hlen?<\/h2><p class=\"uagb-desc-text\">Wir sind bestrebt, allen unseren Kunden verantwortungsvolle und individuelle Tourismuserlebnisse zu bieten.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-b0b4de7f uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Nachhaltigkeit<\/p><\/div><\/div><p class=\"uagb-ifb-desc\">Wir f\u00f6rdern einen verantwortungsvollen Tourismus und stellen sicher, dass unsere Aktivit\u00e4ten den lokalen Gemeinden zugute kommen und die nat\u00fcrliche Umwelt erhalten bleibt.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-b1107157 uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Personalisierung<\/p><\/div><\/div><p class=\"uagb-ifb-desc\">Wir erstellen pers\u00f6nliche Reisepl\u00e4ne, die Ihre Vorlieben widerspiegeln und garantieren Ihnen ein einzigartiges und unvergessliches Erlebnis auf jeder Reise.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-55c87742\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-ce807146 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/www.eventurstp.com\/about\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Mehr lesen<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-537ac0b7 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-95474579\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-99e463d3\"><h3 class=\"uagb-heading-text\">Unsere Zahlen sprechen f\u00fcr sich<\/h3><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-6e6186e9\">\n<div class=\"wp-block-uagb-counter uagb-block-76226e66 wp-block-uagb-counter--number\"><div class=\"wp-block-uagb-counter__number\"><span class=\"uagb-counter-block-number\" data-duration=\"1.5\" data-to-value=\"1000\" data-from-value=\"0\" data-delimiter=\",\"><\/span><span class=\"uagb-counter-block-suffix\">+<\/span><\/div><div class=\"wp-block-uagb-counter__title\">Mehr als 1000 zufriedene Kunden sind mit uns gereist und haben die einzigartige Sch\u00f6nheit von S\u00e3o Tom\u00e9 und Pr\u00edncipe erkundet.<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-counter uagb-block-290a7056 wp-block-uagb-counter--number\"><div class=\"wp-block-uagb-counter__number\"><span class=\"uagb-counter-block-number\" data-duration=\"1.5\" data-to-value=\"95\" data-from-value=\"0\" data-delimiter=\",\"><\/span><span class=\"uagb-counter-block-suffix\">%<\/span><\/div><div class=\"wp-block-uagb-counter__title\">Mit einer Zufriedenheitsrate von 98 Prozent empfehlen unsere Kunden EVENTUR an Freunde und Verwandte weiter.<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uag-hide-mob uagb-block-sf5r8ahe alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-xege72u8 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M96 224C84.72 224 74.05 226.3 64 229.9V224c0-35.3 28.7-64 64-64c17.67 0 32-14.33 32-32S145.7 96 128 96C57.42 96 0 153.4 0 224v96c0 53.02 42.98 96 96 96s96-42.98 96-96S149 224 96 224zM352 224c-11.28 0-21.95 2.305-32 5.879V224c0-35.3 28.7-64 64-64c17.67 0 32-14.33 32-32s-14.33-32-32-32c-70.58 0-128 57.42-128 128v96c0 53.02 42.98 96 96 96s96-42.98 96-96S405 224 352 224z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Was unsere Kunden sagen<\/h2><\/div><p class=\"uagb-ifb-desc\">H\u00f6ren Sie sich die Erfahrungsberichte unserer zufriedenen Kunden an, die sich von der Qualit\u00e4t und dem Wert unserer Pakete und Dienstleistungen \u00fcberzeugt haben.<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-17de2f44 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">5.0<\/h2><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-star-rating uagb-block-880e744b\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-fc743751 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Google Bewertungen<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ndusytbi\">\n<div class=\"wp-block-uagb-container uagb-block-kdvolayk\">\n<div class=\"wp-block-uagb-star-rating uagb-block-akwxejza\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-gtd2jw4f uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">&#8220;Sie sind sehr professionell, ich liebe ihre Dienste. Obwohl sie kein Portugiesisch sprechen, haben sie uns sehr gut bei der \u00dcbersetzung ins Englische geholfen.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-xule0gsg uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/kwadwo.png\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Kwadwo Martey-Baadu<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1w8ekiim\">\n<div class=\"wp-block-uagb-star-rating uagb-block-wbchf88g\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-nhwc14zm uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Ich bin im Juni 2024 mit Eventur nach S\u00e3o Tom\u00e9 gereist. Es waren 5 Sterne. Ein wahres Paradies. Und alles lief nach Plan. Glaubw\u00fcrdiges Unternehmen, gute Unterkunft, super professionelle Reiseleiter. Ein wahr gewordener Traum, den ich wiederholen w\u00fcrde. Vielen Dank an Eventur.      <\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-anv2cmok uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/sonia-150x150.jpg\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Sonia Franco<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-jn5xrdsh\">\n<div class=\"wp-block-uagb-star-rating uagb-block-aoehh63p\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-galfebwp uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">&#8220;Die Erfahrung dieser von Eventur sorgf\u00e4ltig organisierten Reise war ausgezeichnet. Ich kann sie uneingeschr\u00e4nkt empfehlen.&#8221;<br\/><\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-fnxffy1q uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/eventurmiradouro-150x150.jpg\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Solange Mendes<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-7428f41a\">\n<div class=\"wp-block-uagb-container uagb-block-ed80090e\">\n<div class=\"wp-block-uagb-star-rating uagb-block-0fb189cd\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-1732bf53 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">&#8220;Fabelhaft&#8221;<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-7e4b9aff uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/sfa.png\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Sofia Silva<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5e8f8c36\">\n<div class=\"wp-block-uagb-star-rating uagb-block-4749513b\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-d13a9002 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">&#8220;Tolles Reiseb\u00fcro. Unglaubliche Erfahrung, sehr aufmerksame Mitarbeiter, die sich immer um ihre Kunden k\u00fcmmern. Ich kann eine Reise mit Eventur nur empfehlen. 5*&#8221;<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-e1351a39 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/unnamed-1.png\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Miguel Filipe<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a65935bc\">\n<div class=\"wp-block-uagb-star-rating uagb-block-41b7c120\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-bbcf5820 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">&#8220;Eventur Ecotravel hat uns die Reise unseres Lebens geschenkt.<br\/>Das ganze Team hat sich w\u00e4hrend der gesamten Reise super um uns gek\u00fcmmert.<br\/>Vielen Dank daf\u00fcr an Miriam und das Team.<br\/>Unser Guide Sidney, der uns zum Angolares-Wasserfall gef\u00fchrt hat, war 5 Sterne.<br\/>Reise zum Wiederholen.<br\/>Wir nehmen Licht in unsere Herzen \ud83e\udd0d&#8221;<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-67318831 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/smn.png\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">  Sofia Sim\u00f5es<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9bb576d5\">\n<div class=\"wp-block-uagb-container uagb-block-8c2aa677\">\n<div class=\"wp-block-uagb-star-rating uagb-block-57baad56\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-ab74012b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Wir haben Eventur mit der Organisation und Planung unserer Reise nach S\u00e3o Tom\u00e9 beauftragt und alles verlief reibungslos: die Buchung des Hotels, des Autos, des F\u00fchrers und der Aktivit\u00e4ten sowie die Auswahl der Besichtigungen und Wanderungen. Wir waren mit unserer Reise sehr zufrieden. <\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-b7d92943 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/matd.png\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Claire Matondo<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-04f126a3\">\n<div class=\"wp-block-uagb-star-rating uagb-block-5612a871\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-53ef44a5 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">&#8220;Ich hatte eine gro\u00dfartige Zeit und das Reiseunternehmen war gro\u00dfartig. Sie standen in engem Kontakt mit mir und waren sehr hilfreich. Bei allen Fragen, die ich hatte. Alles war wunderbar organisiert und ich sch\u00e4tzte das Wissen, die Freundlichkeit, die Umsicht und die Liebe zum Detail meines Reiseleiters. Ich w\u00fcrde auf jeden Fall wieder mit diesem Unternehmen arbeiten und hoffe, dass ich in dieses Land zur\u00fcckkehren kann, um noch mehr zu erkunden!&#8221;<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-60e8731b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/heather.png\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Heather Coltman<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-27165b1e\">\n<div class=\"wp-block-uagb-star-rating uagb-block-18612b80\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-f3098308 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">5 Sterne!!! Ich empfehle den ausgezeichneten Mietwagenservice! Sicheres Unternehmen! Ich habe aus der Ferne gebucht und alles verlief reibungslos und genau wie vereinbart. Wir haben einen Jimmy f\u00fcr 6 Tage gemietet, die Lieferung und Abholung am Flughafen verlief reibungslos und zur vereinbarten Zeit! Wir werden ihn wieder mieten! Dankesch\u00f6n     <\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-c893f7f9 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/unnamed3.png\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">  Monica Ribeira<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-53341f88 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f73d92fc\"><h2 class=\"uagb-heading-text\">Was unsere Kunden sagen<\/h2><p class=\"uagb-desc-text\">Lesen Sie die Erfahrungsberichte unserer zufriedenen Kunden, die sich von der Qualit\u00e4t und dem Wert unserer Pakete und Dienstleistungen \u00fcberzeugt haben.<\/p><\/div>\n\n\n\n<div style=\"height:51px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?8c9a08b45ffa68905c26408a06e\"><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-eiljrysh alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-3xdblunm\">\n<div class=\"wp-block-uagb-info-box uagb-block-inrxx5pt uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Fesselnde Momente<\/h2><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-gqztgztr uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Lassen Sie sich von den Erfahrungen unserer Reisenden verzaubern!<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-iw0ze7mw\">\n<div class=\"wp-block-uagb-container uagb-block-szi3t8eo\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-4xfpms0r wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/malanzaeventur-1024x768.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/malanzaeventur.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/malanzaeventur.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/malanzaeventur-1024x768.jpg\" alt=\"\" class=\"uag-image-10795\" width=\"384\" height=\"384\" title=\"malanzaeventur\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-wyvxurnb wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/03\/JC0C7481.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/03\/JC0C7481.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/03\/JC0C7481.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2024\/03\/JC0C7481.jpg\" alt=\"\" class=\"uag-image-8878\" width=\"384\" height=\"512\" title=\"JC0C7481\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-qualifd7\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-znx4lawb wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/praiabateriaeventur-1024x758.jpeg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/praiabateriaeventur.jpeg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/praiabateriaeventur.jpeg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/praiabateriaeventur-1024x758.jpeg\" alt=\"\" class=\"uag-image-10791\" width=\"384\" height=\"308\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-5y5nmei9 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/JC0C8408-683x1024.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/JC0C8408-scaled.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/JC0C8408-scaled.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/JC0C8408-683x1024.jpg\" alt=\"\" class=\"uag-image-8698\" width=\"384\" height=\"384\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-yldhniw3 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/tchiloli-1024x682.png ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/tchiloli.png 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/tchiloli.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/tchiloli-1024x682.png\" alt=\"\" class=\"uag-image-10787\" width=\"384\" height=\"288\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-rwbmucdf\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-7zrhzahn wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/eventur-relax-683x1024.jpg ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/eventur-relax.jpg 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/eventur-relax.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/eventur-relax-683x1024.jpg\" alt=\"\" class=\"uag-image-10783\" width=\"384\" height=\"481\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-4ksmckat wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/03\/eventurfamilia-ilheu.png ,https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/03\/eventurfamilia-ilheu.png 780w, https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/03\/eventurfamilia-ilheu.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/03\/eventurfamilia-ilheu.png\" alt=\"\" class=\"uag-image-11011\" width=\"384\" height=\"384\" title=\"\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcber uns Wir schaffen f\u00fcr Sie einzigartige Erlebnisse in S\u00e3o Tom\u00e9 und Pr\u00edncipe. Wir von EVENTUR haben es uns zur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-11295","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v26.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Startseite - Viagens a S\u00e3o Tom\u00e9 e Pr\u00edncipe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eventurstp.com\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Startseite\" \/>\n<meta property=\"og:description\" content=\"\u00dcber uns Wir schaffen f\u00fcr Sie einzigartige Erlebnisse in S\u00e3o Tom\u00e9 und Pr\u00edncipe. Wir von EVENTUR haben es uns zur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eventurstp.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Viagens a S\u00e3o Tom\u00e9 e Pr\u00edncipe\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T11:48:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/EVENTURSTP001-800X600.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Startseite - Viagens a S\u00e3o Tom\u00e9 e Pr\u00edncipe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eventurstp.com\/","og_locale":"de_DE","og_type":"article","og_title":"Startseite","og_description":"\u00dcber uns Wir schaffen f\u00fcr Sie einzigartige Erlebnisse in S\u00e3o Tom\u00e9 und Pr\u00edncipe. Wir von EVENTUR haben es uns zur [&hellip;]","og_url":"https:\/\/www.eventurstp.com\/","og_site_name":"Viagens a S\u00e3o Tom\u00e9 e Pr\u00edncipe","article_modified_time":"2025-09-04T11:48:37+00:00","og_image":[{"url":"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/EVENTURSTP001-800X600.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eventurstp.com\/","url":"https:\/\/www.eventurstp.com\/","name":"Startseite - Viagens a S\u00e3o Tom\u00e9 e Pr\u00edncipe","isPartOf":{"@id":"https:\/\/www.eventurstp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eventurstp.com\/#primaryimage"},"image":{"@id":"https:\/\/www.eventurstp.com\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/EVENTURSTP001-800X600.png","datePublished":"2025-01-27T21:34:43+00:00","dateModified":"2025-09-04T11:48:37+00:00","breadcrumb":{"@id":"https:\/\/www.eventurstp.com\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eventurstp.com\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eventurstp.com\/#primaryimage","url":"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/EVENTURSTP001-800X600.png","contentUrl":"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/EVENTURSTP001-800X600.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eventurstp.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.eventurstp.com\/"},{"@type":"ListItem","position":2,"name":"Startseite"}]},{"@type":"WebSite","@id":"https:\/\/www.eventurstp.com\/#website","url":"https:\/\/www.eventurstp.com\/","name":"Viagens a S\u00e3o Tom\u00e9 e Pr\u00edncipe","description":"Descubra S\u00e3o Tom\u00e9 e Pr\u00edncipe com a Eventur STP. Pacotes personalizados, tours aut\u00eanticos e experi\u00eancias inesquec\u00edveis.","publisher":{"@id":"https:\/\/www.eventurstp.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eventurstp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.eventurstp.com\/#organization","name":"Viagens a S\u00e3o Tom\u00e9 e Pr\u00edncipe","url":"https:\/\/www.eventurstp.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eventurstp.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/cropped-logoeventur.png","contentUrl":"https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/cropped-logoeventur.png","width":1182,"height":304,"caption":"Viagens a S\u00e3o Tom\u00e9 e Pr\u00edncipe"},"image":{"@id":"https:\/\/www.eventurstp.com\/#\/schema\/logo\/image\/"}}]}},"spectra_custom_meta":{"_alp_processed":["1756986517"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"site-post-title":["disabled"],"_last_translation_edit_mode":["translation-editor"],"_edit_last":["1"],"_wp_page_template":[""],"rs_page_bg_color":[""],"_edit_lock":["1754910344:1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:619282:\".wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2e144a4a{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 0px;column-gap: 0px;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d62177b8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 15px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 36px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d62177b8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}[dir=rtl] .uagb-block-d62177b8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 90px;padding-bottom: 90px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 80px;padding-bottom: 80px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 30px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:0.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}\n.uagb-ifb-content>svg *{-webkit-transition:all 0.2s;-o-transition:all 0.2s;transition:all 0.2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=\"rtl\"] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=\"rtl\"] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=\"rtl\"] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}\n.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all 0.3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}\n.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow 0.2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:0.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:0.2;background:rgba(0,0,0,0.5);transition:opacity 0.35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:0.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform 0.35s, opacity 0.35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform 0.4s, opacity 0.4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform 0.45s, opacity 0.45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}\n.uagb-cta__outer-wrap .uagb-cta__content,.uagb-cta__outer-wrap a.uagb-cta__block-link span,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__button-wrapper,.uagb-cta__outer-wrap .uagb-cta-typeof-button,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__outer-wrap .uagb-cta-with-svg{display:inline-block}.uagb-cta__outer-wrap{display:flex;justify-content:space-between}.wp-block-uagb-call-to-action .uagb-cta__buttons{display:inline-flex}.wp-block-uagb-call-to-action .wp-block-button__link,.wp-block-uagb-call-to-action .ast-outline-button{fill:currentColor;justify-content:center}.uagb-cta__button-link-wrapper,.uagb-cta-second__button{display:inline-flex;align-items:center;word-break:keep-all;width:100%}.uagb-cta__title{padding:0;margin:0;display:block}.uagb-cta__content-right .uagb-cta__button-wrapper{float:right}.uagb-cta__link-wrapper.uagb-cta__block-link-style:empty{display:none}a.uagb-cta__block-link,.entry .entry-content a.uagb-cta__block-link,a.uagb-cta__block-link-wrap,.entry .entry-content a.uagb-cta__block-link-wrap{text-decoration:none}a.uagb-cta__block-link:hover,.entry .entry-content a.uagb-cta__block-link:hover,a.uagb-cta__block-link-wrap:hover,.entry .entry-content a.uagb-cta__block-link-wrap:hover .entry .entry-content a.uagb-cta__block-link:hover{color:inherit}.uagb-cta__content-right{text-align:right;justify-content:flex-end}.uagb-cta__left-right-wrap{width:100%;word-break:break-word}.uagb-cta__icon-position-below-title .uagb-cta__left-right-wrap{display:block;min-width:100%;width:100%}.uagb-cta__icon-position-left .uagb-cta__left-right-wrap,.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{display:flex}.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{justify-content:flex-end}.uagb-cta__block-link-icon-after{margin-left:5px;margin-right:0}.uagb-cta__block-link-icon-before{margin-left:0;margin-right:5px}.uagb-cta__block-link-icon,.uagb-cta__block svg{transition:all 200ms linear}.uagb-cta__block{position:relative}.uagb-cta-typeof-button{line-height:1;text-align:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__content-right.uagb-cta__button-valign-middle .uagb-cta__left-right-wrap{display:flex;align-items:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link{justify-content:center}.uagb-cta__link-wrapper a{box-shadow:none;text-decoration:none}.uagb-cta__block,.uagb-cta__content,.uagb-cta__left-right-wrap{z-index:1}.uagb-cta__block-link{cursor:pointer}.uagb-cta__content-right .uagb-cta__block-link{float:right;padding:10px 14px}a.uagb-cta__block-link-wrap{color:inherit}.uagb-cta__content p:empty{display:none}.uagb-cta__button-type-none .uagb-cta__content{width:100%}.uagb-cta-with-svg{height:14px;width:14px;line-height:14px;vertical-align:middle}.uagb-cta__block svg{display:block;height:inherit;width:inherit}.uagb-cta__button-link-wrapper svg{width:20px;height:20px}.uagb-cta__align-button-after{margin-left:5px}.uagb-cta__align-button-before{margin-right:5px}.uagb-cta__block-link i{font-style:normal}a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.wp-block-uagb-call-to-action{position:relative}.wp-block-uagb-call-to-action a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}@media only screen and (max-width: 976px){.uagb-cta__content-stacked-tablet,.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}@media screen and (max-width: 767px){.uagb-cta__content-stacked-mobile,.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}.uagb-cta__desc p:last-child{margin-bottom:0}\n.wp-block-uagb-separator{text-align:center;box-sizing:border-box;line-height:0}.wp-block-uagb-separator__inner{display:inline-block}.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner{display:flex;justify-content:center;align-items:center;margin:0 auto}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::before,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::after,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::after{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--icon .wp-block-uagb-separator-element svg{font-size:30px;color:#333;fill:#333;width:30px;height:30px;line-height:30px;max-width:none}.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{word-break:initial;margin:0}\n.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media (max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media (max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}\n.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow 0.2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}\n.wp-block-uagb-counter .wp-block-uagb-counter__icon,.wp-block-uagb-counter .wp-block-uagb-counter__image-wrap{display:inline-block;line-height:0}.wp-block-uagb-counter--number .wp-block-uagb-counter__number{font-size:52px;color:#3a3a3a}.wp-block-uagb-counter--number .wp-block-uagb-counter__icon{margin-bottom:10px}.wp-block-uagb-counter--bars{display:flex;flex-direction:column}.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container{width:100%;background-color:#eaeaea}.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container .wp-block-uagb-counter__number{width:0%;min-height:5px;text-align:right;line-height:1;white-space:nowrap;overflow:hidden;background:#007cba;display:flex;justify-content:flex-end;align-items:center}.rtl .wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container .wp-block-uagb-counter__number{flex-direction:row-reverse;justify-content:flex-start}.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container .wp-block-uagb-counter__number>:last-child{margin-right:5px}.wp-block-uagb-counter--bars .wp-block-uagb-counter__title{margin-top:15px}.wp-block-uagb-counter--bars .wp-block-uagb-counter__number{color:#fff;padding-top:5px;padding-bottom:5px}.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container{position:relative;display:inline-block;width:100%}.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container .wp-block-uagb-counter__icon svg{width:30px}.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg{pointer-events:none}.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container>svg{transform:rotate(-90deg);width:100%;height:100%}.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container>svg circle{stroke:#eaeaea;stroke-width:1em;fill:transparent}.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container>svg .uagb-counter-circle__progress{stroke:#007cba}.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container__content{position:absolute;left:0;right:0;top:0;bottom:0;display:flex;justify-content:center;align-items:center;flex-direction:column;z-index:1}.wp-block-uagb-counter--circle .wp-block-uagb-counter__number{margin-top:5px;font-size:52px;color:#3a3a3a}.wp-block-uagb-counter--circle .wp-block-uagb-counter__title{margin-top:5px}.wp-block-uagb-counter__icon svg{width:30px}.wp-block-uagb-counter__title{margin-top:10px;margin-bottom:17px;font-size:16px}body[class*=\"astra\"] .wp-block-uagb-counter__title,body[class*=\"astra\"] .wp-block-uagb-counter__number{line-height:normal}\n.wp-block-uagb-star-rating{display:flex}.wp-block-uagb-star-rating .uag-star-rating__title{margin:0}.wp-block-uagb-star-rating .uag-star-rating{display:flex;align-items:center}.wp-block-uagb-star-rating .uag-star{color:#ccd6df;display:inline-block;line-height:0.75em}\n.wp-block-uagb-container.uagb-block-1e5d1737 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1e5d1737 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1e5d1737 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1e5d1737 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1e5d1737 .uagb-container__video-wrap video{opacity: 0.75;background: url(https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/aerial-drone-view-of-the-tropical-ilheu-das-rolas-2023-11-27-05-28-36-utc-scaled.jpg) 50% 50%;;background-size: cover;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e5d1737{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e5d1737 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1e5d1737 .uagb-container__video-wrap{background: var(--ast-global-color-7);;border-color: inherit;}.wp-block-uagb-container.uagb-block-1e5d1737 > div:not(.uagb-container__video-wrap):not(.uagb-container__shape){position: relative;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-1e5d1737{flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1e5d1737{box-shadow: 0px 0px   #00000070 ;padding-top: 285px;padding-bottom: 285px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;row-gap: 0px;column-gap: 0px;overflow: visible;}.uagb-block-cc9d733a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cc9d733a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-cc9d733a .uagb-ifb-icon svg{fill: #333;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cc9d733a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cc9d733a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cc9d733a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cc9d733a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cc9d733a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cc9d733a .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cc9d733a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-cc9d733a.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 14px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cc9d733a.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 36px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cc9d733a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-cc9d733a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-cc9d733a .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-cc9d733a .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cc9d733a .uagb-infobox__content-wrap{text-align: left;}.uagb-block-cc9d733a.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-cc9d733a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 50%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-cc9d733a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 50%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-cc9d733a.wp-block-uagb-info-box .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link{color: #ffffff;background-color: #00000000;}.uagb-block-cc9d733a.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{color: #ffffff;background-color: #00000000;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #ffffff;border-style: solid;}.uagb-block-cc9d733a .uagb-ifb-button-wrapper .uagb-infobox-cta-link svg{fill: #ffffff;}.uagb-block-cc9d733a.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link:hover{color: var(--ast-global-color-7);background-color: #ffffff;border-color: #ffffff;}.uagb-block-cc9d733a .uagb-infobox-cta-link:hover{border-color: #ffffff;}.uagb-block-cc9d733a .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link:hover > svg{fill: var(--ast-global-color-7);}.uagb-block-cc9d733a.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link:focus{color: var(--ast-global-color-7);background-color: #ffffff;border-color: #ffffff;}.uagb-block-cc9d733a .uagb-infobox-cta-link:focus{border-color: #ffffff;}.uagb-block-cc9d733a .uagb-infobox-cta-link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #ffffff;border-style: solid;}.uagb-block-cc9d733a .uagb-ifb-title{font-size: 61px;}[dir=rtl] .uagb-block-cc9d733a .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-da6f24cd .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-da6f24cd .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-da6f24cd .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-da6f24cd .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-da6f24cd .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-da6f24cd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-da6f24cd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 72px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-da6f24cd{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-4);;row-gap: 72px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0%;padding-right: 22%;padding-bottom: 0%;padding-left: 22%;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-0);margin-bottom: 14px;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6 .uagb-heading-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6 .uagb-desc-text{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}.wp-block-uagb-container.uagb-block-29c74af9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-29c74af9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-29c74af9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-29c74af9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-29c74af9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-29c74af9{max-width: 76%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-29c74af9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-29c74af9{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-advanced-heading.uagb-block-23c95072.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-23c95072.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-23c95072.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-23c95072.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-23c95072.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-af8e0f11.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-af8e0f11.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-af8e0f11.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-af8e0f11.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-af8e0f11.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-75936b61 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75936b61 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75936b61 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-75936b61 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-75936b61 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75936b61{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75936b61 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: space-evenly;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-75936b61{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: space-evenly;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-75936b61.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-75936b61.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3cc927cb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-3cc927cb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-3cc927cb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 182px;height: 250px;}.uagb-block-3cc927cb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-3cc927cb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3cc927cb.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c2d11615.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c2d11615.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-c2d11615.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c2d11615.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-c2d11615.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-c2d11615.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-c2d11615.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-c2d11615.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-c2d11615.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-c2d11615.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-c2d11615.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 234px;height: 200px;}.uagb-block-c2d11615.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-c2d11615.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-c2d11615.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c2d11615.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d8e6d73b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-d8e6d73b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-d8e6d73b.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 380px;height: 300px;}.uagb-block-d8e6d73b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-d8e6d73b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d8e6d73b.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-179773c1.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-179773c1.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-179773c1.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-179773c1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-179773c1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-179773c1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-179773c1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-179773c1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-179773c1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-179773c1.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-179773c1.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 330px;height: 200px;}.uagb-block-179773c1.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-179773c1.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-179773c1.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-179773c1.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-rglhekvi .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-rglhekvi .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-rglhekvi .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-rglhekvi .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-rglhekvi .uagb-container__video-wrap video{opacity: 0.7;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-rglhekvi{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-rglhekvi > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 768px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-rglhekvi{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/01\/eventurrolas-scaled.jpg);;background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-rglhekvi::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-7);opacity: 0.3;}.wp-block-uagb-container.uagb-block-lywptp7g .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-lywptp7g .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-lywptp7g .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-lywptp7g .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-lywptp7g .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-lywptp7g{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-lywptp7g > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-lywptp7g{box-shadow: 0px 0px   #00000070 ;padding-top: 72px;padding-bottom: 72px;padding-left: 48px;padding-right: 48px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: inherit;background-color: var(--ast-global-color-5);;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.uagb-block-ag6hx0t4 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ag6hx0t4 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-ag6hx0t4 .uagb-ifb-icon svg{fill: #333;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ag6hx0t4 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ag6hx0t4 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ag6hx0t4 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ag6hx0t4 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ag6hx0t4 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ag6hx0t4 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ag6hx0t4 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-2);margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ag6hx0t4.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ag6hx0t4.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0%;margin-top: 0%;margin-left: 12%;margin-right: 12%;}.uagb-block-ag6hx0t4 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-ag6hx0t4 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-ag6hx0t4 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ag6hx0t4 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ag6hx0t4 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-ag6hx0t4.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-ag6hx0t4 .uagb-ifb-title{font-size: 33px;}.uagb-block-ag6hx0t4 .uagb-ifb-desc{font-size: 26px;}.uagb-block-ag6hx0t4 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-ag6hx0t4 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-edea13a6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-edea13a6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-edea13a6 .uagb-ifb-icon svg{fill: #333;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-edea13a6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-edea13a6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-edea13a6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-edea13a6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-edea13a6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-edea13a6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-edea13a6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-2);margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-edea13a6.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-edea13a6.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0%;margin-top: 0%;margin-left: 12%;margin-right: 12%;}.uagb-block-edea13a6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-edea13a6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-edea13a6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-edea13a6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-edea13a6 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-edea13a6.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-edea13a6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-edea13a6 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-edea13a6 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-71f28efb.wp-block-uagb-call-to-action .uagb-cta__title{margin-bottom: 10px;}.uagb-block-71f28efb.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 11px;}.uagb-block-71f28efb .uagb-cta__align-button-after{margin-left: 10px;}.uagb-block-71f28efb .uagb-cta__align-button-before{margin-right: 10px;}.uagb-block-71f28efb.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 10px;}.uagb-block-71f28efb.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}.uagb-block-71f28efb .uagb-cta__content-wrap{text-align: left;}.uagb-block-71f28efb .uagb-cta__wrap{width: 70%;text-align: left;}.uagb-block-71f28efb.wp-block-uagb-call-to-action{text-align: left;}.uagb-block-71f28efb .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}.uagb-block-71f28efb .uagb-cta__buttons{column-gap: 15px;}.uagb-block-71f28efb.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}.uagb-block-71f28efb .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 70%;}.uagb-block-71f28efb .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-71f28efb.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}.uagb-block-71f28efb.wp-block-uagb-call-to-action  {flex-direction: row;align-items: center;}.uagb-block-71f28efb .uagb-cta__title{font-size: 29px;}.uagb-block-71f28efb .uagb-cta__desc{font-size: 20px;}.wp-block-uagb-container.uagb-block-e8fc30f4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8fc30f4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8fc30f4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8fc30f4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8fc30f4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8fc30f4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8fc30f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: space-between;flex-wrap: wrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-e8fc30f4{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 100px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background: linear-gradient(180deg, var(--ast-global-color-4) 50%, var(--ast-global-color-5) 50%);;background-clip: padding-box;row-gap: 0px;column-gap: 24px;}.uagb-block-c890a0e3.wp-block-uagb-separator{text-align: center;}.uagb-block-c890a0e3.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-c890a0e3 .uagb-separator-spacing-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 100px;padding-left: 0px;}.uagb-block-c890a0e3.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 2px;width: 100%;border-top-color: var(--ast-global-color-6);border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0%;padding-right: 18%;padding-bottom: 6%;padding-left: 18%;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-0);margin-bottom: 14px;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49 .uagb-heading-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49 .uagb-desc-text{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}.wp-block-uagb-container.uagb-block-1e00a9da .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1e00a9da .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1e00a9da .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1e00a9da .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1e00a9da .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e00a9da{max-width: 31%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e00a9da > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 16px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-1e00a9da{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 16px;column-gap: 24px;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2acfa94e.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-2acfa94e.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-2acfa94e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 290px;}.uagb-block-2acfa94e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-2acfa94e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2acfa94e.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8bca7b86 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8bca7b86 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-8bca7b86 .uagb-ifb-icon svg{fill: #333;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8bca7b86 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8bca7b86 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-8bca7b86 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-8bca7b86 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8bca7b86.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 24px;margin-right: 24px;}.uagb-block-8bca7b86.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 24px;margin-right: 24px;}.uagb-block-8bca7b86 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-8bca7b86 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-8bca7b86 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-8bca7b86 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8bca7b86 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-8bca7b86.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-8bca7b86 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}[dir=rtl] .uagb-block-8bca7b86 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-c6ae55bb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c6ae55bb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c6ae55bb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c6ae55bb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c6ae55bb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c6ae55bb{max-width: 31%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c6ae55bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 16px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-c6ae55bb{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 16px;column-gap: 24px;}.uagb-block-937370bc.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-937370bc.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-937370bc.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-937370bc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-937370bc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-937370bc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-937370bc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-937370bc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-937370bc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-937370bc.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-937370bc.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 290px;}.uagb-block-937370bc.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-937370bc.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-937370bc.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-937370bc.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-01946041 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-01946041 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-01946041 .uagb-ifb-icon svg{fill: #333;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-01946041 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-01946041 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-01946041 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-01946041.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-01946041 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-01946041.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 24px;margin-right: 24px;}.uagb-block-01946041.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 24px;margin-right: 24px;}.uagb-block-01946041 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-01946041 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-01946041 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-01946041 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-01946041 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-01946041.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-01946041 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}[dir=rtl] .uagb-block-01946041 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-01946041.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-32ab2baa .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-32ab2baa .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-32ab2baa .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-32ab2baa .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-32ab2baa .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-32ab2baa{max-width: 31%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-32ab2baa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 16px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-32ab2baa{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 16px;column-gap: 24px;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8e3729f7.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-8e3729f7.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-8e3729f7.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 290px;}.uagb-block-8e3729f7.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-8e3729f7.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8e3729f7.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7e775245 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7e775245 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-7e775245 .uagb-ifb-icon svg{fill: #333;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e775245 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e775245 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;}.uagb-block-7e775245 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-7e775245.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 15px;border-radius: 0px;}.uagb-block-7e775245 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e775245.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 24px;margin-right: 24px;}.uagb-block-7e775245.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 24px;margin-right: 24px;}.uagb-block-7e775245 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-7e775245 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-7e775245 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-7e775245 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7e775245 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-7e775245.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7e775245 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}[dir=rtl] .uagb-block-7e775245 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-7e775245.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-a79fbe43 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a79fbe43 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a79fbe43 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a79fbe43 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a79fbe43 .uagb-container__video-wrap video{opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a79fbe43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a79fbe43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a79fbe43{min-height: 60vh;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: fixed;background-image: url(https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-08-at-16.13.37-1.jpeg);;background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a79fbe43::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-7);opacity: 0.2;}.wp-block-uagb-container.uagb-block-6bf09454 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6bf09454 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6bf09454 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6bf09454 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6bf09454 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6bf09454{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6bf09454 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6bf09454{box-shadow: 0px 0px   #00000070 ;padding-top: 96px;padding-bottom: 96px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-0);;row-gap: 0px;column-gap: 0px;}.uagb-block-83ea0154.wp-block-uagb-call-to-action .uagb-cta__title{color: #ffffff;margin-bottom: 14px;}.uagb-block-83ea0154.wp-block-uagb-call-to-action .uagb-cta__desc{color: #ffffff;margin-bottom: 10px;}.uagb-block-83ea0154 .uagb-cta__align-button-after{margin-left: 10px;}.uagb-block-83ea0154 .uagb-cta__align-button-before{margin-right: 10px;}.uagb-block-83ea0154 .uagb-cta__button-wrapper .uagb-cta__block-link svg{fill: #ffffff;}.uagb-block-83ea0154.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 10px;fill: #ffffff;}.uagb-block-83ea0154.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}.uagb-block-83ea0154 .uagb-cta__content-wrap{text-align: left;}.uagb-block-83ea0154 .uagb-cta__wrap{width: 60%;text-align: left;}.uagb-block-83ea0154.wp-block-uagb-call-to-action{text-align: left;}.uagb-block-83ea0154 .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}.uagb-block-83ea0154 .uagb-cta__buttons{column-gap: 15px;}.uagb-block-83ea0154.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}.uagb-block-83ea0154 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 60%;}.uagb-block-83ea0154 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 40%;}.uagb-block-83ea0154.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}.uagb-block-83ea0154.wp-block-uagb-call-to-action  {flex-direction: row;align-items: center;}.uagb-block-83ea0154 .uagb-cta__button-wrapper a.uagb-cta-typeof-button{color: #ffffff;background-color: var(--ast-global-color-2);border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #ffffff;border-style: none;}.uagb-block-83ea0154.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__button-wrapper a.uagb-cta-typeof-button:hover{border-color: #ffffff;}.uagb-block-83ea0154.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__button-wrapper a.uagb-cta-typeof-button:focus{border-color: #ffffff;}.uagb-block-83ea0154.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{color: #ffffff;background-color: var(--ast-global-color-2);border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #ffffff;border-style: none;}.uagb-block-83ea0154.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link:hover{border-color: #ffffff;}.uagb-block-83ea0154.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link:focus{border-color: #ffffff;}.wp-block-uagb-container.uagb-block-4062d932 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4062d932 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4062d932 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4062d932 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4062d932 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4062d932{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4062d932 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4062d932{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-188bf86b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-188bf86b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-188bf86b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-188bf86b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-188bf86b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-188bf86b{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-188bf86b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-188bf86b{min-height: 600px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: calc(50% +  -100px) calc(50% + 0px);background-size: cover;background-attachment: scroll;background-image: url(https:\/\/www.eventurstp.com\/wp-content\/uploads\/2023\/03\/bomBomLove-scaled.jpg);;background-clip: padding-box;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-4ec4096e.wp-block-uagb-image{margin-top: 50px;margin-right: 50px;margin-bottom: 0px;margin-left: 0px;text-align: right;justify-content: flex-end;align-self: flex-end;}.uagb-block-4ec4096e .wp-block-uagb-image__figure{align-items: flex-end;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4ec4096e.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-4ec4096e.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-4ec4096e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 200px;height: 150px;}.uagb-block-4ec4096e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-4ec4096e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4ec4096e.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-58485396 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-58485396 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-58485396 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-58485396 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-58485396 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-58485396{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-58485396 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-58485396{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-afddea9c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 30px;}.wp-block-uagb-advanced-heading.uagb-block-afddea9c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-afddea9c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-afddea9c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-afddea9c .uagb-heading-text{margin-bottom: 14px;}.uagb-block-b0b4de7f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b0b4de7f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-b0b4de7f .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b0b4de7f .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b0b4de7f .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b0b4de7f .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b0b4de7f .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b0b4de7f .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b0b4de7f .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b0b4de7f .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b0b4de7f.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b0b4de7f.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 25px;margin-top: 0px;margin-left: 40px;margin-right: 0px;}.uagb-block-b0b4de7f .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b0b4de7f .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b0b4de7f .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b0b4de7f .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b0b4de7f .uagb-ifb-title{font-family: \"Cabin\";font-weight: 700;font-size: 20px;}[dir=rtl] .uagb-block-b0b4de7f .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b1107157 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b1107157 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-b1107157 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b1107157 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b1107157 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b1107157 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b1107157 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b1107157 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b1107157 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b1107157.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-b1107157 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b1107157.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b1107157.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 25px;margin-top: 0px;margin-left: 40px;margin-right: 0px;}.uagb-block-b1107157 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b1107157 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b1107157 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b1107157 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b1107157 .uagb-ifb-title{font-family: \"Cabin\";font-weight: 700;font-size: 20px;}[dir=rtl] .uagb-block-b1107157 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b1107157.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b1107157.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-b1107157.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-b1107157.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-55c87742.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-55c87742.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-55c87742 .uagb-button__wrapper{margin-top: 20px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-ce807146 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-ce807146 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-ce807146 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-ce807146 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-container.uagb-block-537ac0b7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-537ac0b7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-537ac0b7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-537ac0b7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-537ac0b7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-537ac0b7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-537ac0b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-537ac0b7.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 0px;column-gap: 0px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr)  minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-537ac0b7{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-block-95474579 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-95474579 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-95474579 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-95474579 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-95474579 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-95474579{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-95474579 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-95474579.uagb-layout-grid{row-gap: 0px;column-gap: 0px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-95474579{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;grid-column: span 2;}.wp-block-uagb-advanced-heading.uagb-block-99e463d3.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 200px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-99e463d3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-99e463d3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-99e463d3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-99e463d3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-6e6186e9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6e6186e9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6e6186e9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6e6186e9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6e6186e9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6e6186e9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6e6186e9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6e6186e9.uagb-layout-grid{row-gap: 0px;column-gap: 0px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6e6186e9{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;grid-column: span 2;}.uagb-block-76226e66.wp-block-uagb-counter{text-align: left;padding-top: 0px;padding-right: 72px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{fill: #4B4F58;width: 30px;height: 30px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__title{font-style: normal;color: var(--ast-global-color-3);}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__number{font-style: normal;font-weight: 700;font-size: 65px;color: var(--ast-global-color-2);}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.uagb-block-76226e66.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container{max-width: 230px;}.uagb-block-76226e66.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg circle{stroke-width: 8px;stroke: #eaeaea;r: 111px;cx: 115px;cy: 115px;}.uagb-block-76226e66.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg .uagb-counter-circle__progress{stroke: #007cba;stroke-dasharray: 697.43px;stroke-dashoffset: 697.43px;}.uagb-block-76226e66.wp-block-uagb-counter--bars{flex-direction: column;}.uagb-block-76226e66.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container{background: #eaeaea;}.uagb-block-76226e66.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container .wp-block-uagb-counter__number{background: #007cba;}.uagb-block-290a7056.wp-block-uagb-counter{text-align: left;padding-top: 0px;padding-right: 72px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{fill: #4B4F58;width: 30px;height: 30px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__title{font-style: normal;color: var(--ast-global-color-3);}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__number{font-style: normal;font-weight: 700;font-size: 65px;color: var(--ast-global-color-2);}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.uagb-block-290a7056.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container{max-width: 230px;}.uagb-block-290a7056.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg circle{stroke-width: 8px;stroke: #eaeaea;r: 111px;cx: 115px;cy: 115px;}.uagb-block-290a7056.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg .uagb-counter-circle__progress{stroke: #007cba;stroke-dasharray: 697.43px;stroke-dashoffset: 697.43px;}.uagb-block-290a7056.wp-block-uagb-counter--bars{flex-direction: column;}.uagb-block-290a7056.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container{background: #eaeaea;}.uagb-block-290a7056.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container .wp-block-uagb-counter__number{background: #007cba;}.wp-block-uagb-container.uagb-block-sf5r8ahe .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-sf5r8ahe .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-sf5r8ahe .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-sf5r8ahe .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-sf5r8ahe .uagb-container__video-wrap video{opacity: 0.3;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-sf5r8ahe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-sf5r8ahe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 80px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-sf5r8ahe{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 55% 0%;background-size: cover;background-attachment: fixed;background-image: url(https:\/\/www.eventurstp.com\/wp-content\/uploads\/2025\/03\/eventurfamilia-ilheu.png);;background-clip: padding-box;row-gap: 80px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-sf5r8ahe::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-7);opacity: 0.7;}.uagb-block-xege72u8 .uagb-ifb-icon{width: 53px;line-height: 53px;}.uagb-block-xege72u8 .uagb-ifb-icon > span{font-size: 53px;width: 53px;line-height: 53px;color: #ffffff;}.uagb-block-xege72u8 .uagb-ifb-icon svg{fill: #ffffff;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 53px;height: 53px;line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-xege72u8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-xege72u8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 53px;height: 53px;line-height: 53px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xege72u8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 53px;line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-xege72u8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 53px;line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-xege72u8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xege72u8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-xege72u8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xege72u8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xege72u8.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0%;margin-top: 0%;margin-left: 15%;margin-right: 15%;}.uagb-block-xege72u8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-xege72u8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-xege72u8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-xege72u8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-xege72u8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-xege72u8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-xege72u8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: -30px;margin-left: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-xege72u8 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-xege72u8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-17de2f44 .uagb-ifb-icon{width: 53px;line-height: 53px;}.uagb-block-17de2f44 .uagb-ifb-icon > span{font-size: 53px;width: 53px;line-height: 53px;color: #ffffff;}.uagb-block-17de2f44 .uagb-ifb-icon svg{fill: #ffffff;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 53px;height: 53px;line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-17de2f44 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-17de2f44 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 53px;height: 53px;line-height: 53px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-17de2f44 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 53px;line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-17de2f44 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 53px;line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-17de2f44 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-17de2f44 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-17de2f44 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-17de2f44.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-17de2f44.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0%;margin-top: 0%;margin-left: 15%;margin-right: 15%;}.uagb-block-17de2f44 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-17de2f44 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-17de2f44 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-17de2f44 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-17de2f44 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-17de2f44.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-17de2f44.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: -50px;margin-left: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-17de2f44 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-17de2f44 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;} .uagb-block-880e744b .uag-star-rating{font-size: 20px;} .uagb-block-880e744b .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-880e744b .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-880e744b .uag-star-rating__title{margin-right: 10px;} .uagb-block-880e744b.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: -50px;margin-right: 0px;margin-bottom: -50px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-880e744b .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-880e744b .uag-star:nth-child(5){position: relative;}.uagb-block-fc743751 .uagb-ifb-icon{width: 53px;line-height: 53px;}.uagb-block-fc743751 .uagb-ifb-icon > span{font-size: 53px;width: 53px;line-height: 53px;color: #ffffff;}.uagb-block-fc743751 .uagb-ifb-icon svg{fill: #ffffff;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 53px;height: 53px;line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-fc743751 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-fc743751 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 53px;height: 53px;line-height: 53px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fc743751 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 53px;line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-fc743751 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 53px;line-height: 53px;font-size: 53px;color: #ffffff;fill: #ffffff;}.uagb-block-fc743751 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fc743751 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fc743751 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc743751.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc743751.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0%;margin-top: 0%;margin-left: 15%;margin-right: 15%;}.uagb-block-fc743751 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-fc743751 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-fc743751 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-fc743751 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fc743751 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-fc743751.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-fc743751.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: -18px;margin-right: 0px;margin-bottom: -29px;margin-left: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fc743751 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-fc743751 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-fc743751.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-ndusytbi .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ndusytbi .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ndusytbi .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ndusytbi .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ndusytbi .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ndusytbi{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ndusytbi > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-ndusytbi{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-kdvolayk .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-kdvolayk .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-kdvolayk .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-kdvolayk .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-kdvolayk .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-kdvolayk{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-kdvolayk > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-kdvolayk{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-akwxejza .uag-star-rating{font-size: 20px;} .uagb-block-akwxejza .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-akwxejza .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-akwxejza .uag-star-rating__title{margin-right: 10px;} .uagb-block-akwxejza.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-akwxejza .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-akwxejza .uag-star:nth-child(5){position: relative;}.uagb-block-gtd2jw4f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-gtd2jw4f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-gtd2jw4f .uagb-ifb-icon svg{fill: #333;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-gtd2jw4f .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-gtd2jw4f .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-gtd2jw4f .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-gtd2jw4f .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-gtd2jw4f .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-gtd2jw4f .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-gtd2jw4f .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-gtd2jw4f.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-gtd2jw4f.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-gtd2jw4f .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-gtd2jw4f .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-gtd2jw4f .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-gtd2jw4f .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-gtd2jw4f .uagb-infobox__content-wrap{text-align: center;}.uagb-block-gtd2jw4f.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-gtd2jw4f .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-xule0gsg .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-xule0gsg .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-xule0gsg .uagb-ifb-icon svg{fill: #333;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-xule0gsg .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-xule0gsg .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-xule0gsg .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-xule0gsg.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-xule0gsg.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xule0gsg .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-xule0gsg .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-xule0gsg .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-xule0gsg .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-xule0gsg .uagb-infobox__content-wrap{text-align: center;}.uagb-block-xule0gsg.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-xule0gsg.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-xule0gsg .uagb-ifb-title{text-transform: none;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 0px;}[dir=rtl] .uagb-block-xule0gsg .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-1w8ekiim .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1w8ekiim .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1w8ekiim .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1w8ekiim .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1w8ekiim .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1w8ekiim{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1w8ekiim > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1w8ekiim{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-wbchf88g .uag-star-rating{font-size: 20px;} .uagb-block-wbchf88g .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-wbchf88g .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-wbchf88g .uag-star-rating__title{margin-right: 10px;} .uagb-block-wbchf88g.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-wbchf88g .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-wbchf88g .uag-star:nth-child(5){position: relative;}.uagb-block-nhwc14zm .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-nhwc14zm .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-nhwc14zm .uagb-ifb-icon svg{fill: #333;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-nhwc14zm .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-nhwc14zm .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-nhwc14zm .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-nhwc14zm .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-nhwc14zm .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-nhwc14zm .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-nhwc14zm .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-nhwc14zm.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-nhwc14zm.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-nhwc14zm .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-nhwc14zm .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-nhwc14zm .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-nhwc14zm .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-nhwc14zm .uagb-infobox__content-wrap{text-align: center;}.uagb-block-nhwc14zm.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-nhwc14zm .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-anv2cmok .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-anv2cmok .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-anv2cmok .uagb-ifb-icon svg{fill: #333;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-anv2cmok .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-anv2cmok .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-anv2cmok .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-anv2cmok.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-anv2cmok.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-anv2cmok .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-anv2cmok .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-anv2cmok .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-anv2cmok .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-anv2cmok .uagb-infobox__content-wrap{text-align: center;}.uagb-block-anv2cmok.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-anv2cmok.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-anv2cmok .uagb-ifb-title{text-transform: none;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 0px;}[dir=rtl] .uagb-block-anv2cmok .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-jn5xrdsh .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-jn5xrdsh .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-jn5xrdsh .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-jn5xrdsh .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-jn5xrdsh .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-jn5xrdsh{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-jn5xrdsh > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-jn5xrdsh{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-aoehh63p .uag-star-rating{font-size: 20px;} .uagb-block-aoehh63p .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-aoehh63p .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-aoehh63p .uag-star-rating__title{margin-right: 10px;} .uagb-block-aoehh63p.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-aoehh63p .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-aoehh63p .uag-star:nth-child(5){position: relative;}.uagb-block-galfebwp .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-galfebwp .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-galfebwp .uagb-ifb-icon svg{fill: #333;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-galfebwp .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-galfebwp .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-galfebwp .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-galfebwp .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-galfebwp .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-galfebwp .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-galfebwp .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-galfebwp.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-galfebwp.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-galfebwp .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-galfebwp .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-galfebwp .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-galfebwp .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-galfebwp .uagb-infobox__content-wrap{text-align: center;}.uagb-block-galfebwp.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-galfebwp.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-galfebwp .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-fnxffy1q .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fnxffy1q .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-fnxffy1q .uagb-ifb-icon svg{fill: #333;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fnxffy1q .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fnxffy1q .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-fnxffy1q .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-fnxffy1q.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-fnxffy1q.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fnxffy1q .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-fnxffy1q .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-fnxffy1q .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-fnxffy1q .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fnxffy1q .uagb-infobox__content-wrap{text-align: center;}.uagb-block-fnxffy1q.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fnxffy1q .uagb-ifb-title{text-transform: none;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 0px;}[dir=rtl] .uagb-block-fnxffy1q .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-7428f41a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7428f41a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7428f41a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7428f41a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7428f41a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7428f41a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7428f41a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-7428f41a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-ed80090e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ed80090e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ed80090e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ed80090e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ed80090e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed80090e{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed80090e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ed80090e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-0fb189cd .uag-star-rating{font-size: 20px;} .uagb-block-0fb189cd .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-0fb189cd .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-0fb189cd .uag-star-rating__title{margin-right: 10px;} .uagb-block-0fb189cd.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-0fb189cd .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-0fb189cd .uag-star:nth-child(5){position: relative;}.uagb-block-1732bf53 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1732bf53 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-1732bf53 .uagb-ifb-icon svg{fill: #333;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1732bf53 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1732bf53 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1732bf53 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1732bf53 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1732bf53 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1732bf53 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1732bf53 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-1732bf53.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-1732bf53.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-1732bf53 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-1732bf53 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-1732bf53 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-1732bf53 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1732bf53 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-1732bf53.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-1732bf53.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1732bf53 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-7e4b9aff .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7e4b9aff .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-7e4b9aff .uagb-ifb-icon svg{fill: #333;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e4b9aff .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e4b9aff .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-7e4b9aff .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-7e4b9aff.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e4b9aff.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e4b9aff .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-7e4b9aff .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-7e4b9aff .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-7e4b9aff .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7e4b9aff .uagb-infobox__content-wrap{text-align: center;}.uagb-block-7e4b9aff.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7e4b9aff .uagb-ifb-title{text-transform: none;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 0px;}[dir=rtl] .uagb-block-7e4b9aff .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-5e8f8c36 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5e8f8c36 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5e8f8c36 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5e8f8c36 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5e8f8c36 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5e8f8c36{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5e8f8c36 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5e8f8c36{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-4749513b .uag-star-rating{font-size: 20px;} .uagb-block-4749513b .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-4749513b .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-4749513b .uag-star-rating__title{margin-right: 10px;} .uagb-block-4749513b.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-4749513b .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-4749513b .uag-star:nth-child(5){position: relative;}.uagb-block-d13a9002 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d13a9002 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d13a9002 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d13a9002 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d13a9002 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d13a9002 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d13a9002 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d13a9002 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d13a9002 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d13a9002 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-d13a9002.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d13a9002.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d13a9002 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d13a9002 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d13a9002 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d13a9002 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d13a9002 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d13a9002.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d13a9002.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d13a9002 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e1351a39 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e1351a39 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-e1351a39 .uagb-ifb-icon svg{fill: #333;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e1351a39 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e1351a39 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39 .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-e1351a39.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-e1351a39 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-e1351a39.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-e1351a39.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-e1351a39 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-e1351a39 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-e1351a39 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-e1351a39 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e1351a39 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-e1351a39.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-e1351a39.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-e1351a39 .uagb-ifb-title{text-transform: none;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 0px;}[dir=rtl] .uagb-block-e1351a39 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-a65935bc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a65935bc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a65935bc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a65935bc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a65935bc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a65935bc{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a65935bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a65935bc{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-41b7c120 .uag-star-rating{font-size: 20px;} .uagb-block-41b7c120 .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-41b7c120 .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-41b7c120 .uag-star-rating__title{margin-right: 10px;} .uagb-block-41b7c120.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-41b7c120 .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-41b7c120 .uag-star:nth-child(5){position: relative;}.uagb-block-bbcf5820 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bbcf5820 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-bbcf5820 .uagb-ifb-icon svg{fill: #333;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bbcf5820 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bbcf5820 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bbcf5820 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bbcf5820 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bbcf5820 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bbcf5820 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bbcf5820 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-bbcf5820.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bbcf5820.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bbcf5820 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-bbcf5820 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-bbcf5820 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-bbcf5820 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bbcf5820 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-bbcf5820.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-bbcf5820.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bbcf5820 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-67318831 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-67318831 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-67318831 .uagb-ifb-icon svg{fill: #333;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-67318831 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-67318831 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831 .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-67318831.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-67318831 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-67318831.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-67318831.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-67318831 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-67318831 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-67318831 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-67318831 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-67318831 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-67318831.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-67318831.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-67318831 .uagb-ifb-title{text-transform: none;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 0px;}[dir=rtl] .uagb-block-67318831 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-67318831.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-9bb576d5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9bb576d5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9bb576d5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9bb576d5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9bb576d5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9bb576d5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9bb576d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-9bb576d5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-8c2aa677 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8c2aa677 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8c2aa677 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8c2aa677 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8c2aa677 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8c2aa677{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8c2aa677 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8c2aa677{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-57baad56 .uag-star-rating{font-size: 20px;} .uagb-block-57baad56 .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-57baad56 .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-57baad56 .uag-star-rating__title{margin-right: 10px;} .uagb-block-57baad56.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-57baad56 .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-57baad56 .uag-star:nth-child(5){position: relative;}.uagb-block-ab74012b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ab74012b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-ab74012b .uagb-ifb-icon svg{fill: #333;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ab74012b .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ab74012b .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ab74012b .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ab74012b .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ab74012b .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ab74012b .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ab74012b .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-ab74012b.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ab74012b.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ab74012b .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-ab74012b .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-ab74012b .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ab74012b .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ab74012b .uagb-infobox__content-wrap{text-align: center;}.uagb-block-ab74012b.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-ab74012b.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ab74012b .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b7d92943 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b7d92943 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b7d92943 .uagb-ifb-icon svg{fill: #333;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b7d92943 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b7d92943 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943 .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-b7d92943.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-b7d92943 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b7d92943.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-b7d92943.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b7d92943 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b7d92943 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b7d92943 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b7d92943 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b7d92943 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-b7d92943.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-b7d92943.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b7d92943 .uagb-ifb-title{text-transform: none;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 0px;}[dir=rtl] .uagb-block-b7d92943 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-04f126a3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-04f126a3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-04f126a3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-04f126a3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-04f126a3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-04f126a3{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-04f126a3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-04f126a3{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-5612a871 .uag-star-rating{font-size: 20px;} .uagb-block-5612a871 .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-5612a871 .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-5612a871 .uag-star-rating__title{margin-right: 10px;} .uagb-block-5612a871.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-5612a871 .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-5612a871 .uag-star:nth-child(5){position: relative;}.uagb-block-53ef44a5 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-53ef44a5 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-53ef44a5 .uagb-ifb-icon svg{fill: #333;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-53ef44a5 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-53ef44a5 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-53ef44a5 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-53ef44a5 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-53ef44a5 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-53ef44a5 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-53ef44a5 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-53ef44a5.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-53ef44a5.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-53ef44a5 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-53ef44a5 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-53ef44a5 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-53ef44a5 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-53ef44a5 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-53ef44a5.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-53ef44a5.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-53ef44a5 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-60e8731b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-60e8731b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-60e8731b .uagb-ifb-icon svg{fill: #333;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-60e8731b .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-60e8731b .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-60e8731b.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-60e8731b .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-60e8731b.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-60e8731b.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-60e8731b .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-60e8731b .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-60e8731b .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-60e8731b .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-60e8731b .uagb-infobox__content-wrap{text-align: center;}.uagb-block-60e8731b.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-60e8731b.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-60e8731b .uagb-ifb-title{text-transform: none;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 0px;}[dir=rtl] .uagb-block-60e8731b .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-27165b1e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27165b1e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27165b1e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27165b1e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27165b1e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27165b1e{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27165b1e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-27165b1e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-18612b80 .uag-star-rating{font-size: 20px;} .uagb-block-18612b80 .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-18612b80 .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-18612b80 .uag-star-rating__title{margin-right: 10px;} .uagb-block-18612b80.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-18612b80 .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-18612b80 .uag-star:nth-child(5){position: relative;}.uagb-block-f3098308 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f3098308 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-f3098308 .uagb-ifb-icon svg{fill: #333;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f3098308 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f3098308 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f3098308 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f3098308 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f3098308 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f3098308 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f3098308 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-f3098308.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-f3098308.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-f3098308 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-f3098308 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-f3098308 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-f3098308 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f3098308 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-f3098308.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-f3098308.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f3098308 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-f3098308.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c893f7f9 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c893f7f9 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-c893f7f9 .uagb-ifb-icon svg{fill: #333;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c893f7f9 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c893f7f9 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9 .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-c893f7f9 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c893f7f9.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-c893f7f9.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c893f7f9 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-c893f7f9 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-c893f7f9 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c893f7f9 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c893f7f9 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-c893f7f9.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-c893f7f9.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-c893f7f9 .uagb-ifb-title{text-transform: none;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 0px;}[dir=rtl] .uagb-block-c893f7f9 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-53341f88 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-53341f88 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-53341f88 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-53341f88 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-53341f88 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-53341f88{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-53341f88 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-53341f88{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-3);;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f73d92fc.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-f73d92fc.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-f73d92fc.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-5);margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f73d92fc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f73d92fc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f73d92fc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f73d92fc .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-container.uagb-block-eiljrysh .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eiljrysh .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eiljrysh .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eiljrysh .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eiljrysh .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eiljrysh{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eiljrysh > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 80px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-eiljrysh{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-0);;row-gap: 80px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3xdblunm .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3xdblunm .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3xdblunm .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3xdblunm .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3xdblunm .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3xdblunm{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3xdblunm > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-3xdblunm{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.uagb-block-inrxx5pt .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-inrxx5pt .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-inrxx5pt .uagb-ifb-icon svg{fill: #333;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-inrxx5pt .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-inrxx5pt .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-inrxx5pt .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-inrxx5pt .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-inrxx5pt .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-inrxx5pt .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-inrxx5pt .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-inrxx5pt.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-inrxx5pt.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-4);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-inrxx5pt .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-inrxx5pt .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-inrxx5pt .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-inrxx5pt .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-inrxx5pt .uagb-infobox__content-wrap{text-align: left;}.uagb-block-inrxx5pt.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-inrxx5pt .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-gqztgztr .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-gqztgztr .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-gqztgztr .uagb-ifb-icon svg{fill: #333;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-gqztgztr .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-gqztgztr .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-gqztgztr .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-gqztgztr .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-gqztgztr .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-gqztgztr .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-gqztgztr .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-gqztgztr.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-gqztgztr.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-4);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-gqztgztr .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-gqztgztr .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-gqztgztr .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-gqztgztr .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-gqztgztr .uagb-infobox__content-wrap{text-align: left;}.uagb-block-gqztgztr.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-gqztgztr.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-gqztgztr .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-iw0ze7mw .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-iw0ze7mw .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-iw0ze7mw .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-iw0ze7mw .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-iw0ze7mw .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-iw0ze7mw{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-iw0ze7mw > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-iw0ze7mw{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-szi3t8eo .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-szi3t8eo .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-szi3t8eo .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-szi3t8eo .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-szi3t8eo .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-szi3t8eo{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-szi3t8eo > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-szi3t8eo{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.uagb-block-4xfpms0r.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-4xfpms0r .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4xfpms0r.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-4xfpms0r.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-4xfpms0r.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 384px;}.uagb-block-4xfpms0r.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-4xfpms0r.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-wyvxurnb.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-wyvxurnb .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-wyvxurnb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-wyvxurnb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-wyvxurnb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 512px;}.uagb-block-wyvxurnb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-wyvxurnb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-qualifd7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-qualifd7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-qualifd7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-qualifd7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-qualifd7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-qualifd7{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-qualifd7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-qualifd7{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.uagb-block-znx4lawb.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-znx4lawb .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-znx4lawb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-znx4lawb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-znx4lawb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 308px;}.uagb-block-znx4lawb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-znx4lawb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5y5nmei9.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-5y5nmei9 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5y5nmei9.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5y5nmei9.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5y5nmei9.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 384px;}.uagb-block-5y5nmei9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5y5nmei9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-yldhniw3.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-yldhniw3 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-yldhniw3.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-yldhniw3.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-yldhniw3.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 288px;}.uagb-block-yldhniw3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-yldhniw3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-rwbmucdf .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-rwbmucdf .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-rwbmucdf .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-rwbmucdf .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-rwbmucdf .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-rwbmucdf{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-rwbmucdf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-rwbmucdf{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.uagb-block-7zrhzahn.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-7zrhzahn .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-7zrhzahn.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-7zrhzahn.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-7zrhzahn.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 481px;}.uagb-block-7zrhzahn.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-7zrhzahn.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4ksmckat.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4ksmckat.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-4ksmckat.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-4ksmckat.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: contain;width: 384px;height: 384px;}.uagb-block-4ksmckat.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-4ksmckat.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e5d1737{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e5d1737 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1e5d1737{min-height: 85vh;padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cc9d733a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cc9d733a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cc9d733a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cc9d733a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cc9d733a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 45px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 45px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-cc9d733a .uagb-infobox-cta-link{border-style: solid;border-color: #ffffff;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-da6f24cd{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-da6f24cd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 48px;}.wp-block-uagb-container.uagb-block-da6f24cd{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-4);;row-gap: 48px;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 120px;padding-bottom: 0px;padding-left: 120px;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6 .uagb-heading-text{font-size: 25px;margin-bottom: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-29c74af9{max-width: 80%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-29c74af9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-29c74af9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75936b61{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75936b61 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-75936b61{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-3cc927cb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 230px;height: 150px;}.uagb-block-c2d11615.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 230px;height: 120px;}.uagb-block-d8e6d73b.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 230px;height: 181px;}.uagb-block-179773c1.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 230px;height: 121px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-rglhekvi{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-rglhekvi > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 500px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-rglhekvi{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-rglhekvi::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-lywptp7g{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-lywptp7g > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-lywptp7g{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 24px;column-gap: 0px;}.uagb-block-ag6hx0t4 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ag6hx0t4.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ag6hx0t4.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ag6hx0t4 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ag6hx0t4 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ag6hx0t4 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ag6hx0t4 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ag6hx0t4 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ag6hx0t4.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-ag6hx0t4 .uagb-ifb-title{font-size: 23px;}.uagb-block-ag6hx0t4 .uagb-ifb-desc{font-size: 18px;}.uagb-block-ag6hx0t4 .uagb-ifb-title-prefix{font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-edea13a6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-edea13a6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-edea13a6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-edea13a6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-edea13a6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-edea13a6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-edea13a6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edea13a6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edea13a6.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-edea13a6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-edea13a6 .uagb-ifb-desc{font-size: 14px;}.uagb-block-edea13a6 .uagb-ifb-title-prefix{font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-71f28efb.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}.uagb-block-71f28efb.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}.uagb-block-71f28efb .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-71f28efb .uagb-cta__wrap{text-align: center;}.uagb-block-71f28efb.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}.uagb-block-71f28efb .uagb-cta__desc{font-size: 23px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8fc30f4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8fc30f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 24px;}.wp-block-uagb-container.uagb-block-e8fc30f4{padding-top: 0px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(180deg, var(--ast-global-color-4) 50%, var(--ast-global-color-5) 50%);;background-clip: padding-box;column-gap: 24px;}.uagb-block-c890a0e3.wp-block-uagb-separator{text-align: center;}.uagb-block-c890a0e3.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-c890a0e3 .uagb-separator-spacing-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 80px;padding-left: 0px;}.uagb-block-c890a0e3.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: var(--ast-global-color-6);border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 120px;padding-bottom: 48px;padding-left: 120px;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49 .uagb-heading-text{font-size: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e00a9da{max-width: 31%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e00a9da > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1e00a9da{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-2acfa94e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 342px;height: 165px;}.uagb-block-8bca7b86.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 12px;margin-right: 12px;}.uagb-block-8bca7b86.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 12px;margin-right: 12px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8bca7b86 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8bca7b86 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8bca7b86 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-8bca7b86 .uagb-ifb-title{font-size: 20px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c6ae55bb{max-width: 31%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c6ae55bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c6ae55bb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-937370bc.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 342px;height: 165px;}.uagb-block-01946041.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 12px;margin-right: 12px;}.uagb-block-01946041.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 12px;margin-right: 12px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-01946041 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-01946041 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-01946041 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-01946041 .uagb-ifb-title{font-size: 20px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-32ab2baa{max-width: 31%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-32ab2baa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-32ab2baa{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-8e3729f7.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 342px;height: 165px;}.uagb-block-7e775245.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 12px;margin-right: 12px;}.uagb-block-7e775245.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 12px;margin-right: 12px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7e775245 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7e775245 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7e775245 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7e775245 .uagb-ifb-title{font-size: 20px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a79fbe43{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a79fbe43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a79fbe43{min-height: 40vh;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-a79fbe43::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6bf09454{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6bf09454 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6bf09454{padding-top: 48px;padding-bottom: 48px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-0);;}.uagb-block-83ea0154.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}.uagb-block-83ea0154.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}.uagb-block-83ea0154 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 40%;}.uagb-block-83ea0154 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 60%;}.uagb-block-83ea0154 .uagb-cta__wrap{width: 40%;text-align: left;}.uagb-block-83ea0154.wp-block-uagb-call-to-action {flex-direction: row;align-items: center;}.uagb-block-83ea0154.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: none;border-color: #ffffff;}.uagb-block-83ea0154.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: none;border-color: #ffffff;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4062d932{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4062d932 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;}.wp-block-uagb-container.uagb-block-4062d932{padding-top: 80px;padding-bottom: 60px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-188bf86b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-188bf86b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-188bf86b{min-height: 550px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-position: calc(50% +  -72px) calc(50% + 0px);background-size: cover;background-clip: padding-box;}.uagb-block-4ec4096e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 200px;height: 150px;}.uagb-block-4ec4096e.wp-block-uagb-image{margin-top: 24px;margin-right: 24px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-58485396{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-58485396 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 16px;}.wp-block-uagb-container.uagb-block-58485396{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 16px;}.wp-block-uagb-advanced-heading.uagb-block-afddea9c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-afddea9c .uagb-heading-text{font-size: 25px;margin-bottom: 10px;}.uagb-block-b0b4de7f.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b0b4de7f.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 42px;margin-right: 0px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b0b4de7f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b0b4de7f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b0b4de7f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b0b4de7f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b0b4de7f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b0b4de7f .uagb-ifb-title{font-size: 18px;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b1107157.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b1107157.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 42px;margin-right: 0px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b1107157 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b1107157 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b1107157 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b1107157 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b1107157 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b1107157 .uagb-ifb-title{font-size: 18px;}[dir=rtl] .uagb-block-b1107157.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-55c87742.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-55c87742.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-55c87742 .uagb-button__wrapper{margin-top: 10px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-537ac0b7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-537ac0b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-537ac0b7.uagb-layout-grid > .uagb-container-inner-blocks-wrap{grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr)  minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-537ac0b7{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-95474579{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-95474579 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-95474579.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-95474579{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 2;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-advanced-heading.uagb-block-99e463d3.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6e6186e9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6e6186e9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6e6186e9.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6e6186e9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;grid-column: span 2;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-76226e66.wp-block-uagb-counter{padding-top: 0px;padding-right: 36px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__title{font-size: 14px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__number{font-size: 45px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.uagb-block-290a7056.wp-block-uagb-counter{padding-top: 0px;padding-right: 36px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__title{font-size: 14px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__number{font-size: 45px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-sf5r8ahe{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-sf5r8ahe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-sf5r8ahe{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-sf5r8ahe::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-block-sf5r8ahe.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-sf5r8ahe.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-xege72u8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xege72u8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xege72u8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0%;margin-top: 0%;margin-left: 8%;margin-right: 8%;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 53px;height: 53px;line-height: 53px;font-size: 53px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 53px;font-size: 53px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-xege72u8 .uagb-ifb-icon{width: 53px;line-height: 53px;}.uagb-block-xege72u8 .uagb-ifb-icon > span{font-size: 53px;width: 53px;line-height: 53px;}.uagb-block-xege72u8 .uagb-iconbox-icon-wrap{width: 53px;height: 53px;line-height: 53px;}.uagb-block-xege72u8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-xege72u8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-xege72u8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-xege72u8 .uagb-ifb-title{font-size: 25px;}.uagb-block-xege72u8 .uagb-ifb-title-prefix{font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-17de2f44 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-17de2f44.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-17de2f44.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0%;margin-top: 0%;margin-left: 8%;margin-right: 8%;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 53px;height: 53px;line-height: 53px;font-size: 53px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 53px;font-size: 53px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-17de2f44 .uagb-ifb-icon{width: 53px;line-height: 53px;}.uagb-block-17de2f44 .uagb-ifb-icon > span{font-size: 53px;width: 53px;line-height: 53px;}.uagb-block-17de2f44 .uagb-iconbox-icon-wrap{width: 53px;height: 53px;line-height: 53px;}.uagb-block-17de2f44 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-17de2f44 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-17de2f44.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-17de2f44 .uagb-ifb-title-prefix{font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;} .uagb-block-880e744b.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-880e744b .uag-star-rating__title {margin-bottom: 0;} .uagb-block-880e744b .uag-star-rating__title{margin-right: 10px;} .uagb-block-880e744b .uag-star-rating{font-size: 22px;}.uagb-block-fc743751 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc743751.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc743751.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0%;margin-top: 0%;margin-left: 8%;margin-right: 8%;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 53px;height: 53px;line-height: 53px;font-size: 53px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 53px;font-size: 53px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fc743751 .uagb-ifb-icon{width: 53px;line-height: 53px;}.uagb-block-fc743751 .uagb-ifb-icon > span{font-size: 53px;width: 53px;line-height: 53px;}.uagb-block-fc743751 .uagb-iconbox-icon-wrap{width: 53px;height: 53px;line-height: 53px;}.uagb-block-fc743751 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-fc743751 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-fc743751.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fc743751 .uagb-ifb-title-prefix{font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ndusytbi{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ndusytbi > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-ndusytbi{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-ndusytbi.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-ndusytbi.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-kdvolayk{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-kdvolayk > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-kdvolayk{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-kdvolayk.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-kdvolayk.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-akwxejza.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-akwxejza .uag-star-rating__title {margin-bottom: 0;} .uagb-block-akwxejza .uag-star-rating__title{margin-right: 10px;} .uagb-block-akwxejza .uag-star-rating{font-size: 22px;}.uagb-block-gtd2jw4f.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-gtd2jw4f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-gtd2jw4f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-gtd2jw4f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-gtd2jw4f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gtd2jw4f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-xule0gsg.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-xule0gsg.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-xule0gsg .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-xule0gsg .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-xule0gsg .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-xule0gsg .uagb-ifb-title{font-size: 16px;line-height: 1em;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1w8ekiim{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1w8ekiim > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-1w8ekiim{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-1w8ekiim.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-1w8ekiim.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-wbchf88g.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-wbchf88g .uag-star-rating__title {margin-bottom: 0;} .uagb-block-wbchf88g .uag-star-rating__title{margin-right: 10px;} .uagb-block-wbchf88g .uag-star-rating{font-size: 22px;}.uagb-block-nhwc14zm.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-nhwc14zm .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-nhwc14zm .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-nhwc14zm .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-nhwc14zm .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-nhwc14zm .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-anv2cmok.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-anv2cmok.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-anv2cmok .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-anv2cmok .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-anv2cmok .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-anv2cmok .uagb-ifb-title{font-size: 16px;line-height: 1em;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-jn5xrdsh{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-jn5xrdsh > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-jn5xrdsh{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-jn5xrdsh.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-jn5xrdsh.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-aoehh63p.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-aoehh63p .uag-star-rating__title {margin-bottom: 0;} .uagb-block-aoehh63p .uag-star-rating__title{margin-right: 10px;} .uagb-block-aoehh63p .uag-star-rating{font-size: 22px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-galfebwp .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-galfebwp .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-galfebwp .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-galfebwp .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-galfebwp .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-galfebwp.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-fnxffy1q.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-fnxffy1q.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fnxffy1q .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fnxffy1q .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fnxffy1q .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fnxffy1q .uagb-ifb-title{font-size: 16px;line-height: 1em;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7428f41a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7428f41a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-7428f41a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-7428f41a.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-7428f41a.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed80090e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed80090e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-ed80090e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-ed80090e.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-ed80090e.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-0fb189cd.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-0fb189cd .uag-star-rating__title {margin-bottom: 0;} .uagb-block-0fb189cd .uag-star-rating__title{margin-right: 10px;} .uagb-block-0fb189cd .uag-star-rating{font-size: 22px;}.uagb-block-1732bf53.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1732bf53 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1732bf53 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1732bf53 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1732bf53 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1732bf53 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1732bf53.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-7e4b9aff.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e4b9aff.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7e4b9aff .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7e4b9aff .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7e4b9aff .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7e4b9aff .uagb-ifb-title{font-size: 16px;line-height: 1em;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5e8f8c36{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5e8f8c36 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-5e8f8c36{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-5e8f8c36.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-5e8f8c36.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-4749513b.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-4749513b .uag-star-rating__title {margin-bottom: 0;} .uagb-block-4749513b .uag-star-rating__title{margin-right: 10px;} .uagb-block-4749513b .uag-star-rating{font-size: 22px;}.uagb-block-d13a9002.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d13a9002 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d13a9002 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d13a9002 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d13a9002 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d13a9002 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d13a9002.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e1351a39.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-e1351a39.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39 .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39 .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e1351a39 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e1351a39 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e1351a39 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e1351a39.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-e1351a39 .uagb-ifb-title{font-size: 16px;line-height: 1em;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39 .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39 .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a65935bc{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a65935bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-a65935bc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-a65935bc.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-a65935bc.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-41b7c120.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-41b7c120 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-41b7c120 .uag-star-rating__title{margin-right: 10px;} .uagb-block-41b7c120 .uag-star-rating{font-size: 22px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bbcf5820 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bbcf5820 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bbcf5820 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bbcf5820 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bbcf5820 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-67318831.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-67318831.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831 .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831 .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-67318831 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-67318831 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-67318831 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-67318831.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-67318831 .uagb-ifb-title{font-size: 16px;line-height: 1em;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831 .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831 .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9bb576d5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9bb576d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-9bb576d5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-9bb576d5.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-9bb576d5.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8c2aa677{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8c2aa677 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-8c2aa677{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-8c2aa677.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-8c2aa677.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-57baad56.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-57baad56 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-57baad56 .uag-star-rating__title{margin-right: 10px;} .uagb-block-57baad56 .uag-star-rating{font-size: 22px;}.uagb-block-ab74012b.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ab74012b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ab74012b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ab74012b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ab74012b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ab74012b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ab74012b.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b7d92943.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-b7d92943.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943 .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943 .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b7d92943 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b7d92943 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b7d92943 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b7d92943.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b7d92943 .uagb-ifb-title{font-size: 16px;line-height: 1em;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943 .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943 .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-04f126a3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-04f126a3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-04f126a3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-04f126a3.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-04f126a3.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-5612a871.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-5612a871 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-5612a871 .uag-star-rating__title{margin-right: 10px;} .uagb-block-5612a871 .uag-star-rating{font-size: 22px;}.uagb-block-53ef44a5.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-53ef44a5 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-53ef44a5 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-53ef44a5 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-53ef44a5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-53ef44a5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-60e8731b.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-60e8731b.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-60e8731b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-60e8731b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-60e8731b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-60e8731b.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-60e8731b .uagb-ifb-title{font-size: 16px;line-height: 1em;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27165b1e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27165b1e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-27165b1e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-27165b1e.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-27165b1e.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-18612b80.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-18612b80 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-18612b80 .uag-star-rating__title{margin-right: 10px;} .uagb-block-18612b80 .uag-star-rating{font-size: 22px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f3098308 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f3098308 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-f3098308 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-f3098308 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3098308 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3098308.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c893f7f9.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-c893f7f9.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9 .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9 .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c893f7f9 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c893f7f9 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c893f7f9 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-c893f7f9 .uagb-ifb-title{font-size: 16px;line-height: 1em;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9 .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9 .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-53341f88{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-53341f88 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-53341f88{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-3);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eiljrysh{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eiljrysh > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-eiljrysh{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-0);;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-eiljrysh.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-eiljrysh.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3xdblunm{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3xdblunm > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-3xdblunm{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-3xdblunm.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-3xdblunm.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-inrxx5pt .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-inrxx5pt .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-inrxx5pt .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-inrxx5pt .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-inrxx5pt .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-inrxx5pt.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-inrxx5pt .uagb-ifb-title{font-size: 25px;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-gqztgztr .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-gqztgztr .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-gqztgztr .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-gqztgztr .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gqztgztr .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-iw0ze7mw{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-iw0ze7mw > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-iw0ze7mw{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-iw0ze7mw.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-iw0ze7mw.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-szi3t8eo{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-szi3t8eo > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-szi3t8eo{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;column-gap: 0px;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4xfpms0r.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 250px;}.uagb-block-4xfpms0r.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-4xfpms0r .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-wyvxurnb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 300px;}.uagb-block-wyvxurnb.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-wyvxurnb .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-qualifd7{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-qualifd7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-qualifd7{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;column-gap: 0px;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-znx4lawb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 220px;}.uagb-block-znx4lawb.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-znx4lawb .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5y5nmei9.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 200px;}.uagb-block-5y5nmei9.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-5y5nmei9 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-yldhniw3.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 250px;}.uagb-block-yldhniw3.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-yldhniw3 .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-rwbmucdf{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-rwbmucdf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-rwbmucdf{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;column-gap: 0px;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-7zrhzahn.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 250px;}.uagb-block-7zrhzahn.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-7zrhzahn .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4ksmckat.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 384px;height: 300px;}.uagb-block-4ksmckat.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-4ksmckat .wp-block-uagb-image__figure{align-items: flex-start;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e5d1737{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e5d1737 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-1e5d1737{flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1e5d1737{min-height: 65vh;padding-top: 100px;padding-bottom: 100px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cc9d733a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cc9d733a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cc9d733a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cc9d733a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cc9d733a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-cc9d733a .uagb-infobox-cta-link{border-style: solid;border-color: #ffffff;}.uagb-block-cc9d733a .uagb-ifb-title{font-size: 40px;}[dir=rtl] .uagb-block-cc9d733a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-da6f24cd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-da6f24cd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 36px;}.wp-block-uagb-container.uagb-block-da6f24cd{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;row-gap: 36px;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c8330bd6 .uagb-heading-text{font-size: 23px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-29c74af9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-29c74af9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-29c74af9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-75936b61{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-75936b61 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: nowrap;row-gap: 24px;column-gap: 12px;}.wp-block-uagb-container.uagb-block-75936b61{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 24px;column-gap: 12px;order: initial;flex-wrap: nowrap;}.uagb-block-3cc927cb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 140px;height: 90px;}.uagb-block-c2d11615.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 220px;height: 70px;}.uagb-block-d8e6d73b.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 200px;height: 120px;}.uagb-block-179773c1.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 160px;height: 70px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-rglhekvi{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-rglhekvi > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-rglhekvi{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-rglhekvi::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-lywptp7g{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-lywptp7g > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-lywptp7g{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;flex-wrap: wrap;}.uagb-block-ag6hx0t4 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ag6hx0t4.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ag6hx0t4.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ag6hx0t4 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ag6hx0t4 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ag6hx0t4 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ag6hx0t4 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ag6hx0t4 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ag6hx0t4.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-ag6hx0t4 .uagb-ifb-title{font-size: 22px;}.uagb-block-ag6hx0t4 .uagb-ifb-desc{font-size: 14px;}.uagb-block-ag6hx0t4 .uagb-ifb-title-prefix{font-size: 15px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-ag6hx0t4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-edea13a6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-edea13a6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-edea13a6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-edea13a6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edea13a6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-edea13a6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-edea13a6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-edea13a6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-edea13a6.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-edea13a6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-edea13a6 .uagb-ifb-desc{font-size: 13px;}.uagb-block-edea13a6 .uagb-ifb-title-prefix{font-size: 15px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-edea13a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-71f28efb.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 1px;}.uagb-block-71f28efb.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}.uagb-block-71f28efb.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}.uagb-block-71f28efb .uagb-cta__buttons{justify-content: center;}.uagb-block-71f28efb .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-71f28efb .uagb-cta__wrap{text-align: center;}.uagb-block-71f28efb.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}.uagb-block-71f28efb .uagb-cta__title{font-size: 23px;}.uagb-block-71f28efb .uagb-cta__desc{font-size: 14px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8fc30f4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8fc30f4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e8fc30f4{padding-top: 0px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;row-gap: 0px;column-gap: 0px;order: initial;background: linear-gradient(180deg, var(--ast-global-color-4) 50%, var(--ast-global-color-5) 50%);;background-clip: padding-box;}.uagb-block-c890a0e3.wp-block-uagb-separator{text-align: center;}.uagb-block-c890a0e3.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-c890a0e3 .uagb-separator-spacing-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 62px;padding-left: 0px;}.uagb-block-c890a0e3.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: var(--ast-global-color-6);border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 24px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-4f6acc49 .uagb-heading-text{font-size: 22px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1e00a9da{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1e00a9da > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 12px;}.wp-block-uagb-container.uagb-block-1e00a9da{padding-top: 0px;padding-bottom: 48px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 12px;order: initial;flex-wrap: wrap;}.uagb-block-2acfa94e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 770px;height: 200px;}.uagb-block-8bca7b86 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8bca7b86.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 46px;margin-right: 36px;}.uagb-block-8bca7b86.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 36px;margin-right: 36px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: border-box;}.uagb-block-8bca7b86 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8bca7b86 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8bca7b86 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-image-content img{width: 100%;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100%;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100%;}.uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100%;}.uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-8bca7b86 .uagb-ifb-title{font-size: 23px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8bca7b86.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c6ae55bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c6ae55bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 12px;}.wp-block-uagb-container.uagb-block-c6ae55bb{padding-top: 0px;padding-bottom: 48px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 12px;order: initial;flex-wrap: wrap;}.uagb-block-937370bc.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 770px;height: 200px;}.uagb-block-01946041 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-01946041.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 46px;margin-right: 36px;}.uagb-block-01946041.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 36px;margin-right: 36px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: border-box;}.uagb-block-01946041 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-01946041 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-01946041 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-image-content img{width: 100%;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100%;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100%;}.uagb-block-01946041 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100%;}.uagb-block-01946041.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-01946041 .uagb-ifb-title{font-size: 23px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01946041.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-32ab2baa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-32ab2baa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 12px;}.wp-block-uagb-container.uagb-block-32ab2baa{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 12px;order: initial;flex-wrap: wrap;}.uagb-block-8e3729f7.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 770px;height: 200px;}.uagb-block-7e775245 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e775245.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 46px;margin-right: 36px;}.uagb-block-7e775245.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 36px;margin-right: 36px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: border-box;}.uagb-block-7e775245 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7e775245 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7e775245 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 14px;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-image-content img{width: 100%;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 100%;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 100%;}.uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 100%;}.uagb-block-7e775245.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7e775245 .uagb-ifb-title{font-size: 23px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7e775245.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a79fbe43{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a79fbe43 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a79fbe43{min-height: 40vh;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-a79fbe43::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6bf09454{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6bf09454 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6bf09454{padding-top: 72px;padding-bottom: 72px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-0);;}.uagb-block-83ea0154.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 36px;}.uagb-block-83ea0154.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}.uagb-block-83ea0154.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}.uagb-block-83ea0154 .uagb-cta__buttons{justify-content: center;}.uagb-block-83ea0154 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 80%;}.uagb-block-83ea0154 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 20%;}.uagb-block-83ea0154 .uagb-cta__wrap{width: 80%;text-align: center;}.uagb-block-83ea0154.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-83ea0154.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: none;border-color: #ffffff;}.uagb-block-83ea0154.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: none;border-color: #ffffff;}.uagb-block-83ea0154 .uagb-cta__desc{font-size: 21px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4062d932{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4062d932 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4062d932{padding-top: 64px;padding-bottom: 48px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-188bf86b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-188bf86b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;justify-content: flex-end;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-188bf86b{min-height: 300px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-position: calc(50% +  0px) calc(50% + 0px);background-size: cover;background-clip: padding-box;align-items: flex-start;justify-content: flex-end;flex-wrap: wrap;}.uagb-block-4ec4096e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 200px;height: 150px;}.uagb-block-4ec4096e.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: -24px;margin-left: 0px;text-align: right;justify-content: flex-end;align-self: flex-end;}.uagb-block-4ec4096e .wp-block-uagb-image__figure{align-items: flex-end;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-58485396{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-58485396 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-58485396{padding-top: 48px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-afddea9c .uagb-heading-text{font-size: 23px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b0b4de7f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b0b4de7f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b0b4de7f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b0b4de7f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b0b4de7f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b0b4de7f .uagb-ifb-title{font-size: 18px;}.uagb-block-b0b4de7f .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b0b4de7f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b1107157 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b1107157 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b1107157 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b1107157 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b1107157 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b1107157.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b1107157 .uagb-ifb-title{font-size: 18px;}.uagb-block-b1107157 .uagb-ifb-desc{font-size: 14px;}[dir=rtl] .uagb-block-b1107157.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-55c87742.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-55c87742.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-537ac0b7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-537ac0b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-537ac0b7.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 36px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-537ac0b7{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;row-gap: 36px;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-95474579{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-95474579 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-95474579.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-95474579{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;grid-column: span 2;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-advanced-heading.uagb-block-99e463d3.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6e6186e9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6e6186e9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6e6186e9.uagb-layout-grid{row-gap: 24px;column-gap: 24px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6e6186e9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 24px;order: initial;grid-column: span 2;grid-row: span 1;align-self: stretch;justify-self: stretch;}.wp-block-uagb-container.uagb-block-6e6186e9.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-6e6186e9.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-76226e66.wp-block-uagb-counter{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__title{font-size: 14px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__number{font-size: 39px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-76226e66.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.uagb-block-290a7056.wp-block-uagb-counter{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__title{font-size: 14px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__number{font-size: 39px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-290a7056.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-sf5r8ahe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-sf5r8ahe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: wrap;align-content: center;row-gap: 36px;}.wp-block-uagb-container.uagb-block-sf5r8ahe{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 36px;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-sf5r8ahe::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-block-sf5r8ahe.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-sf5r8ahe.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-xege72u8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xege72u8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xege72u8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 53px;height: 53px;line-height: 53px;font-size: 53px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 53px;font-size: 53px;}.uagb-block-xege72u8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-xege72u8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-xege72u8 .uagb-ifb-icon{width: 53px;line-height: 53px;}.uagb-block-xege72u8 .uagb-ifb-icon > span{font-size: 53px;width: 53px;line-height: 53px;}.uagb-block-xege72u8 .uagb-iconbox-icon-wrap{width: 53px;height: 53px;line-height: 53px;}.uagb-block-xege72u8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-xege72u8 .uagb-ifb-title{font-size: 23px;}.uagb-block-xege72u8 .uagb-ifb-title-prefix{font-size: 15px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-xege72u8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-17de2f44 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-17de2f44.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-17de2f44.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 53px;height: 53px;line-height: 53px;font-size: 53px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 53px;font-size: 53px;}.uagb-block-17de2f44 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-17de2f44 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-17de2f44 .uagb-ifb-icon{width: 53px;line-height: 53px;}.uagb-block-17de2f44 .uagb-ifb-icon > span{font-size: 53px;width: 53px;line-height: 53px;}.uagb-block-17de2f44 .uagb-iconbox-icon-wrap{width: 53px;height: 53px;line-height: 53px;}.uagb-block-17de2f44.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-17de2f44 .uagb-ifb-title-prefix{font-size: 15px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-17de2f44.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;} .uagb-block-880e744b.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-880e744b .uag-star-rating__title {margin-bottom: 0;} .uagb-block-880e744b .uag-star-rating__title{margin-right: 10px;} .uagb-block-880e744b .uag-star-rating{font-size: 20px;}.uagb-block-fc743751 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc743751.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc743751.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 53px;height: 53px;line-height: 53px;font-size: 53px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 53px;font-size: 53px;}.uagb-block-fc743751 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-fc743751 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 53px;line-height: 53px;font-size: 53px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fc743751 .uagb-ifb-icon{width: 53px;line-height: 53px;}.uagb-block-fc743751 .uagb-ifb-icon > span{font-size: 53px;width: 53px;line-height: 53px;}.uagb-block-fc743751 .uagb-iconbox-icon-wrap{width: 53px;height: 53px;line-height: 53px;}.uagb-block-fc743751.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fc743751.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fc743751 .uagb-ifb-title-prefix{font-size: 15px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-fc743751.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ndusytbi{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ndusytbi > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-ndusytbi{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-kdvolayk{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-kdvolayk > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-kdvolayk{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-akwxejza.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-akwxejza .uag-star-rating__title {margin-bottom: 0;} .uagb-block-akwxejza .uag-star-rating__title{margin-right: 10px;} .uagb-block-akwxejza .uag-star-rating{font-size: 20px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-gtd2jw4f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gtd2jw4f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-gtd2jw4f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-gtd2jw4f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-gtd2jw4f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-gtd2jw4f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-xule0gsg.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-xule0gsg.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-xule0gsg .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-xule0gsg .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-xule0gsg .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-xule0gsg .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-xule0gsg .uagb-ifb-title{font-size: 15px;line-height: 1em;}[dir=rtl] .uagb-block-xule0gsg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1w8ekiim{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1w8ekiim > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-1w8ekiim{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-wbchf88g.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-wbchf88g .uag-star-rating__title {margin-bottom: 0;} .uagb-block-wbchf88g .uag-star-rating__title{margin-right: 10px;} .uagb-block-wbchf88g .uag-star-rating{font-size: 20px;}.uagb-block-nhwc14zm.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-nhwc14zm .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-nhwc14zm .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-nhwc14zm .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-nhwc14zm .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-nhwc14zm .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-nhwc14zm.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-anv2cmok.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-anv2cmok.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-anv2cmok .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-anv2cmok .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-anv2cmok .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-anv2cmok .uagb-ifb-title{font-size: 15px;line-height: 1em;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-anv2cmok.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-jn5xrdsh{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-jn5xrdsh > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-jn5xrdsh{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-aoehh63p.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-aoehh63p .uag-star-rating__title {margin-bottom: 0;} .uagb-block-aoehh63p .uag-star-rating__title{margin-right: 10px;} .uagb-block-aoehh63p .uag-star-rating{font-size: 20px;}.uagb-block-galfebwp.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-galfebwp .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-galfebwp .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-galfebwp .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-galfebwp .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-galfebwp .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-galfebwp.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-galfebwp.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-fnxffy1q.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-fnxffy1q.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fnxffy1q .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fnxffy1q .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fnxffy1q .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fnxffy1q .uagb-ifb-title{font-size: 15px;line-height: 1em;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fnxffy1q.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7428f41a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7428f41a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-7428f41a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed80090e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed80090e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-ed80090e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-0fb189cd.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-0fb189cd .uag-star-rating__title {margin-bottom: 0;} .uagb-block-0fb189cd .uag-star-rating__title{margin-right: 10px;} .uagb-block-0fb189cd .uag-star-rating{font-size: 20px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1732bf53 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1732bf53 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1732bf53 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1732bf53 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1732bf53 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1732bf53.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-7e4b9aff.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e4b9aff.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7e4b9aff .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7e4b9aff .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7e4b9aff .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-7e4b9aff .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7e4b9aff .uagb-ifb-title{font-size: 15px;line-height: 1em;}[dir=rtl] .uagb-block-7e4b9aff.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5e8f8c36{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5e8f8c36 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-5e8f8c36{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-4749513b.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-4749513b .uag-star-rating__title {margin-bottom: 0;} .uagb-block-4749513b .uag-star-rating__title{margin-right: 10px;} .uagb-block-4749513b .uag-star-rating{font-size: 20px;}.uagb-block-d13a9002.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d13a9002 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d13a9002 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d13a9002 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d13a9002 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d13a9002 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d13a9002.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d13a9002.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e1351a39.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-e1351a39.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e1351a39 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e1351a39 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e1351a39 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e1351a39.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-e1351a39 .uagb-ifb-title{font-size: 15px;line-height: 1em;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e1351a39.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a65935bc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a65935bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-a65935bc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-41b7c120.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-41b7c120 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-41b7c120 .uag-star-rating__title{margin-right: 10px;} .uagb-block-41b7c120 .uag-star-rating{font-size: 20px;}.uagb-block-bbcf5820.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bbcf5820 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bbcf5820 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bbcf5820 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bbcf5820 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bbcf5820 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bbcf5820.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-67318831.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-67318831.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-67318831 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-67318831 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-67318831 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-67318831.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-67318831 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-67318831.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-67318831 .uagb-ifb-title{font-size: 15px;line-height: 1em;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-67318831.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9bb576d5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9bb576d5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-9bb576d5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8c2aa677{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8c2aa677 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-8c2aa677{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-57baad56.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-57baad56 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-57baad56 .uag-star-rating__title{margin-right: 10px;} .uagb-block-57baad56 .uag-star-rating{font-size: 20px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ab74012b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ab74012b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ab74012b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ab74012b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ab74012b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ab74012b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b7d92943.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-b7d92943.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b7d92943 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b7d92943 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b7d92943 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b7d92943.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b7d92943.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-b7d92943 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b7d92943 .uagb-ifb-title{font-size: 15px;line-height: 1em;}[dir=rtl] .uagb-block-b7d92943.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-04f126a3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-04f126a3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-04f126a3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-5612a871.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-5612a871 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-5612a871 .uag-star-rating__title{margin-right: 10px;} .uagb-block-5612a871 .uag-star-rating{font-size: 20px;}.uagb-block-53ef44a5.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-53ef44a5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-53ef44a5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-53ef44a5 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-53ef44a5 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-53ef44a5 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-53ef44a5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-60e8731b.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-60e8731b.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-60e8731b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-60e8731b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-60e8731b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-60e8731b.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-60e8731b .uagb-ifb-title{font-size: 15px;line-height: 1em;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-60e8731b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27165b1e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27165b1e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-27165b1e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-18612b80.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-18612b80 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-18612b80 .uag-star-rating__title{margin-right: 10px;} .uagb-block-18612b80 .uag-star-rating{font-size: 20px;}.uagb-block-f3098308.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-f3098308 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3098308 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f3098308 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f3098308 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-f3098308 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-f3098308.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-f3098308.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f3098308.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c893f7f9.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-c893f7f9.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c893f7f9 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c893f7f9 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c893f7f9 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-c893f7f9 .uagb-ifb-title{font-size: 15px;line-height: 1em;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c893f7f9.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-53341f88{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-53341f88 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-53341f88{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-3);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eiljrysh{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eiljrysh > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-eiljrysh{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-0);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3xdblunm{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3xdblunm > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3xdblunm{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 20px;column-gap: 0px;order: initial;align-items: stretch;flex-wrap: wrap;}.uagb-block-inrxx5pt.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-inrxx5pt .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-inrxx5pt .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-inrxx5pt .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-inrxx5pt .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-inrxx5pt .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-inrxx5pt .uagb-ifb-title{font-size: 23px;}[dir=rtl] .uagb-block-inrxx5pt.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-gqztgztr.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-gqztgztr .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gqztgztr .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-gqztgztr .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-gqztgztr .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-gqztgztr .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-gqztgztr.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-gqztgztr.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-gqztgztr.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-iw0ze7mw{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-iw0ze7mw > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-iw0ze7mw{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-szi3t8eo{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-szi3t8eo > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-szi3t8eo{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4xfpms0r.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4xfpms0r.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 250px;}.uagb-block-4xfpms0r.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-4xfpms0r .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-wyvxurnb.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-wyvxurnb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 600px;height: 250px;}.uagb-block-wyvxurnb.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-wyvxurnb .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-qualifd7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-qualifd7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-qualifd7{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-znx4lawb.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-znx4lawb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 600px;height: 250px;}.uagb-block-znx4lawb.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-znx4lawb .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5y5nmei9.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5y5nmei9.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 250px;}.uagb-block-5y5nmei9.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-5y5nmei9 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-yldhniw3.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-yldhniw3.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 250px;}.uagb-block-yldhniw3.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-yldhniw3 .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-rwbmucdf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-rwbmucdf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-rwbmucdf{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-7zrhzahn.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-7zrhzahn.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 600px;height: 250px;}.uagb-block-7zrhzahn.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-7zrhzahn .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4ksmckat.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4ksmckat.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 250px;}.uagb-block-4ksmckat.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-4ksmckat .wp-block-uagb-image__figure{align-items: flex-start;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2e144a4a{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 0px;column-gap: 0px;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d62177b8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 15px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 36px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d62177b8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}[dir=rtl] .uagb-block-d62177b8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 90px;padding-bottom: 90px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 80px;padding-bottom: 80px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 30px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2e144a4a{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 0px;column-gap: 0px;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d62177b8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 15px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 36px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d62177b8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}[dir=rtl] .uagb-block-d62177b8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 90px;padding-bottom: 90px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 80px;padding-bottom: 80px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 30px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2e144a4a{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 0px;column-gap: 0px;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d62177b8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 15px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 36px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d62177b8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}[dir=rtl] .uagb-block-d62177b8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 90px;padding-bottom: 90px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 80px;padding-bottom: 80px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 30px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2e144a4a{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 0px;column-gap: 0px;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d62177b8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 15px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 36px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d62177b8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}[dir=rtl] .uagb-block-d62177b8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 90px;padding-bottom: 90px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 80px;padding-bottom: 80px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 30px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e144a4a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2e144a4a{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-7);;row-gap: 0px;column-gap: 0px;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d62177b8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 15px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 36px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d62177b8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d62177b8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 10%;padding-bottom: 0%;padding-left: 10%;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-d62177b8 .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 900;font-size: 12px;letter-spacing: 1px;}[dir=rtl] .uagb-block-d62177b8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 90px;padding-bottom: 90px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 96px;padding-bottom: 0px;padding-left: 96px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e144a4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e144a4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2e144a4a{padding-top: 80px;padding-bottom: 80px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-7);;}.uagb-block-d62177b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 30px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d62177b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d62177b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d62177b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d62177b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}\";s:2:\"js\";s:1060:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-ce807146' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBCounter.init( '.uagb-block-76226e66', {\"layout\":\"number\",\"heading\":\"Mais de 1000 clientes satisfeitos viajaram conosco, explorando a beleza u00fanica de Su00e3o Tomu00e9 e Pru00edncipe.\",\"numberPrefix\":\"\",\"numberSuffix\":\"+\",\"startNumber\":0,\"endNumber\":1000,\"totalNumber\":1000,\"decimalPlaces\":0,\"animationDuration\":1500,\"thousandSeparator\":\",\",\"circleSize\":230,\"circleStokeSize\":8,\"isFrontend\":true} );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBCounter.init( '.uagb-block-290a7056', {\"layout\":\"number\",\"heading\":\"Com uma taxa de satisfau00e7u00e3o de 98%, os nossos clientes recomendam a EVENTUR a amigos e familiares.\",\"numberPrefix\":\"\",\"numberSuffix\":\"%\",\"startNumber\":0,\"endNumber\":95,\"totalNumber\":100,\"decimalPlaces\":0,\"animationDuration\":1500,\"thousandSeparator\":\",\",\"circleSize\":230,\"circleStokeSize\":8,\"isFrontend\":true} );\n});\n });\";s:18:\"current_block_list\";a:19:{i:0;s:14:\"uagb\/container\";i:1;s:13:\"uagb\/info-box\";i:3;s:21:\"uagb\/advanced-heading\";i:5;s:10:\"uagb\/image\";i:6;s:19:\"uagb\/call-to-action\";i:8;s:14:\"uagb\/separator\";i:9;s:12:\"uagb\/buttons\";i:10;s:18:\"uagb\/buttons-child\";i:12;s:12:\"uagb\/counter\";i:13;s:16:\"uagb\/star-rating\";i:15;s:11:\"core\/spacer\";i:16;s:14:\"core\/shortcode\";i:17;s:14:\"core\/paragraph\";i:18;s:11:\"core\/search\";i:19;s:10:\"core\/group\";i:20;s:12:\"core\/heading\";i:21;s:17:\"core\/latest-posts\";i:22;s:13:\"core\/archives\";i:23;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784111314\";s:6:\"gfonts\";a:1:{s:5:\"Cabin\";a:2:{s:10:\"fontfamily\";s:5:\"Cabin\";s:12:\"fontvariants\";a:1:{i:0;s:3:\"700\";}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"_uag_css_file_name":["uag-css-11295.css"],"_uag_js_file_name":["uag-js-11295.js"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Eventur","author_link":"https:\/\/www.eventurstp.com\/de\/author\/master\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00dcber uns Wir schaffen f\u00fcr Sie einzigartige Erlebnisse in S\u00e3o Tom\u00e9 und Pr\u00edncipe. Wir von EVENTUR haben es uns zur [&hellip;]","_links":{"self":[{"href":"https:\/\/www.eventurstp.com\/de\/wp-json\/wp\/v2\/pages\/11295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eventurstp.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eventurstp.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eventurstp.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eventurstp.com\/de\/wp-json\/wp\/v2\/comments?post=11295"}],"version-history":[{"count":4,"href":"https:\/\/www.eventurstp.com\/de\/wp-json\/wp\/v2\/pages\/11295\/revisions"}],"predecessor-version":[{"id":11431,"href":"https:\/\/www.eventurstp.com\/de\/wp-json\/wp\/v2\/pages\/11295\/revisions\/11431"}],"wp:attachment":[{"href":"https:\/\/www.eventurstp.com\/de\/wp-json\/wp\/v2\/media?parent=11295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}